{"id":29880,"date":"2023-06-05T12:35:40","date_gmt":"2023-06-05T10:35:40","guid":{"rendered":"https:\/\/www.dbu.de\/?post_type=termine&#038;p=29880"},"modified":"2023-09-14T13:37:04","modified_gmt":"2023-09-14T11:37:04","slug":"dbudigital-online-salon-flachenkonkurrenz-durch-photovoltaik-anlagen-aktuelle-entwicklungen-und-losungskonzepte","status":"publish","type":"termine","link":"https:\/\/www.dbu.de\/en\/termine\/dbudigital-online-salon-flachenkonkurrenz-durch-photovoltaik-anlagen-aktuelle-entwicklungen-und-losungskonzepte\/","title":{"rendered":"#DBUdigital Online-Salon \u201eFl\u00e4chenkonkurrenz durch Photovoltaik-Anlagen \u2013 Aktuelle Entwicklungen und L\u00f6sungskonzepte\u201c"},"content":{"rendered":"\n<div class=\"wp-block-wordpress-dbu-dbu-container\">\n<p class=\"wp-block-paragraph\">11.09.2023 14:00 bis 16:00 Uhr<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Photovoltaik (PV) ist neben der Windenergie ein wichtiger Baustein der Energiewende. Zwar gilt eine erste Priorit\u00e4t der Installation von PV-Anlagen auf Dachfl\u00e4chen, ohne Freifl\u00e4chen-PV-Anlagen wird es jedoch nicht m\u00f6glich sein, die Ziele der Energiewende zu erreichen. Daraus ergibt sich eine mehr oder minder stark ausgepr\u00e4gte Fl\u00e4chenkonkurrenz mit anderen Landnutzungen und auch dem Naturschutz. Ziel der Veranstaltung ist es, einen \u00dcberblick zu geben \u00fcber die aktuellen Entwicklungen der PV auf Freifl\u00e4chen und interessante, zukunftsf\u00e4hige L\u00f6sungen aufzuzeigen. Dabei geht es unter anderem um Agri-PV, die Entwicklungen von PV-Kraftwerken in Gleisbetten sowie die Entwicklung und Umsetzung von Zertifizierungsans\u00e4tzen f\u00fcr Freifl\u00e4chenanlagen. Zudem wird es auch darum gehen, aktuelle Herausforderungen \u2013 unter anderem aus der Perspektive der Landwirtschaft und des Naturschutzes \u2013 aufzuzeigen sowie rechtliche Implikationen und Fragen der Akzeptanz zu beschreiben, um daraus m\u00f6gliche L\u00f6sungen abzuleiten.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Die Veranstaltung richtet sich an eine breite Zielgruppe \u2013 Projektierende, Planungsb\u00fcros, Kommunen, Umwelt- und Naturschutzverb\u00e4nde sowie interessierte B\u00fcrgerinnen und B\u00fcrger.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Programm<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Begr\u00fc\u00dfung<\/strong><br>Alexander Bonde, DBU-Generalsekret\u00e4r<\/li>\n\n\n\n<li><strong>Einf\u00fchrung und Einordnung des Themas<\/strong><br>Felix Gruber, DBU-Abteilungsleiter Umwelttechnik<\/li>\n\n\n\n<li><strong>Fachvortr\u00e4ge<\/strong>\n<ul class=\"wp-block-list\">\n<li><strong>Vertikale Agri-Photovoltaik im Ackerbau<\/strong><br>Lisa-Marie Bieber, <a rel=\"noreferrer noopener\" href=\"https:\/\/www.ise.fraunhofer.de\/de\/forschungsprojekte\/vackerbio.html\" target=\"_blank\">Fraunhofer-Institut f\u00fcr Solare Energiesysteme ISE<\/a><\/li>\n\n\n\n<li><strong>Modulare PV-Panelsysteme zur automatischen Flie\u00dfmontage von PV-Kraftwerken im Gleis<\/strong><br>Dr. Achim Fricker, <a rel=\"noreferrer noopener\" href=\"https:\/\/qinum.com\/\" target=\"_blank\">QINUM GmbH<\/a><\/li>\n\n\n\n<li><strong>Evaluierungssystem f\u00fcr eine umweltfreundliche und landschaftsvertr\u00e4gliche Energiewende<\/strong><br>Andreas Engl, <a rel=\"noreferrer noopener\" href=\"https:\/\/regionalwerke.com\/das-projekt-eule\/\" target=\"_blank\">Regionalwerke GmbH &amp; Co. KG<\/a><\/li>\n<\/ul>\n<\/li>\n\n\n\n<li><strong>Erweiterte Gespr\u00e4chs- und Fragerunde im Austausch mit allen Zuh\u00f6renden<\/strong>\n<ul class=\"wp-block-list\">\n<li>Lisa-Marie Bieber, <a rel=\"noreferrer noopener\" href=\"https:\/\/www.ise.fraunhofer.de\/de\/leitthemen\/integrierte-photovoltaik\/agri-photovoltaik-agri-pv.html\" target=\"_blank\">Fraunhofer-Institut f\u00fcr Solare Energiesysteme ISE<\/a><\/li>\n\n\n\n<li>Dr. Achim Fricker, <a rel=\"noreferrer noopener\" href=\"https:\/\/qinum.com\/\" target=\"_blank\">QINUM GmbH<\/a><\/li>\n\n\n\n<li>Andreas Engl, <a rel=\"noreferrer noopener\" href=\"https:\/\/regionalwerke.com\/das-projekt-eule\/\" target=\"_blank\">Regionalwerke GmbH &amp; Co. KG<\/a><\/li>\n\n\n\n<li>Kathrin Ammermann, <a rel=\"noreferrer noopener\" href=\"https:\/\/www.bfn.de\/\" target=\"_blank\">Bundesamt f\u00fcr Naturschutz (BfN)<\/a><\/li>\n\n\n\n<li>Dr. Nils Wegner, <a rel=\"noreferrer noopener\" href=\"https:\/\/stiftung-umweltenergierecht.de\/\" target=\"_blank\">Stiftung Umweltenergierecht<\/a><\/li>\n\n\n\n<li>Mona von Baumbach, <a rel=\"noreferrer noopener\" href=\"https:\/\/www.lee-nds-hb.de\/\" target=\"_blank\">Landesverband Erneuerbare Energien Niedersachsen \/ Bremen e. V.<\/a><\/li>\n<\/ul>\n<\/li>\n\n\n\n<li><strong>Fazit<\/strong><br>Felix Gruber, DBU-Abteilungsleiter Umwelttechnik<\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Moderation<\/strong>: Dr. Katrin Anneser (DBU), Melanie Vogelpohl (DBU) &amp; Dr. Volker Wachend\u00f6rfer (DBU)<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Wir freuen uns auf Sie!<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Aufzeichnung<\/h3>\n\n\n<div class='dbu-youtube'><div class='dbu-youtube__default'><\/div><div class='dbu-youtube__video'><div id=\"GKgYRyInSBg-6a97699c1e7e0\" data-video-id=\"GKgYRyInSBg\" class=\"ma-gdpr-youtube-wrapper\" style=\"width:100%;aspect-ratio:16\/9;\" data-new-window=\"\" data-yt-parameters=\"\"><picture class=\"ma-gdpr-youtube-thumbnail\"><source media=\"(min-width:640px)\" type=\"image\/webp\" srcset=\"\/\/www.dbu.de\/app\/uploads\/ma-gdpr-youtube-thumbnails\/GKgYRyInSBg\/GKgYRyInSBg_hq720.webp\"><source media=\"(min-width:640px)\" type=\"image\/jpeg\" srcset=\"\/\/www.dbu.de\/app\/uploads\/ma-gdpr-youtube-thumbnails\/GKgYRyInSBg\/GKgYRyInSBg_hq720.jpg\"><source media=\"(min-width:320px)\" type=\"image\/webp\" srcset=\"\/\/www.dbu.de\/app\/uploads\/ma-gdpr-youtube-thumbnails\/GKgYRyInSBg\/GKgYRyInSBg_sddefault.webp\"><source media=\"(min-width:320px)\" type=\"image\/jpeg\" srcset=\"\/\/www.dbu.de\/app\/uploads\/ma-gdpr-youtube-thumbnails\/GKgYRyInSBg\/GKgYRyInSBg_sddefault.jpg\"><source media=\"(min-width:240px)\" type=\"image\/webp\" srcset=\"\/\/www.dbu.de\/app\/uploads\/ma-gdpr-youtube-thumbnails\/GKgYRyInSBg\/GKgYRyInSBg_hqdefault.webp\"><source media=\"(min-width:240px)\" type=\"image\/jpeg\" srcset=\"\/\/www.dbu.de\/app\/uploads\/ma-gdpr-youtube-thumbnails\/GKgYRyInSBg\/GKgYRyInSBg_hqdefault.jpg\"><img decoding=\"async\" src=\"\/\/www.dbu.de\/app\/uploads\/ma-gdpr-youtube-thumbnails\/GKgYRyInSBg\/GKgYRyInSBg_mqdefault.jpg\" alt=\"YouTube Datenschutz\" \"><\/picture><svg class=\"ma-gdpr-youtube-button button-youtube \" ><use xlink:href=\"#ma-gdpr-youtube-play-button-youtube\"><\/use><\/svg><div class=\"ma-gdpr-youtube-notice \" style=\"font-size:.7em; \">When clicked, this video is loaded from YouTube and data is send to YouTube. See our <a class=\"privacy-policy-link\" href=\"https:\/\/www.dbu.de\/en\/imprint-privacy\/\" rel=\"privacy-policy\">Imprint &amp; Privacy<\/a>.<\/div><\/div><\/div><\/div><\/div>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":2,"featured_media":45526,"template":"","meta":{"footnotes":""},"categories":[12,13],"tags":[],"class_list":["post-29880","termine","type-termine","status-publish","has-post-thumbnail","hentry","category-dbu","category-zuk"],"meta_box":{"dbu_termin_start":"2023-09-11 14:00","dbu_termin_end":"2023-09-11 16:00","dbu_termin_veranstalter":"","dbu_headerimage_cover":"","dbu_submenu":"","dbu_submenu_position":"","dbu_submenu_entry":[]},"_links":{"self":[{"href":"https:\/\/www.dbu.de\/en\/wp-json\/wp\/v2\/termine\/29880","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.dbu.de\/en\/wp-json\/wp\/v2\/termine"}],"about":[{"href":"https:\/\/www.dbu.de\/en\/wp-json\/wp\/v2\/types\/termine"}],"author":[{"embeddable":true,"href":"https:\/\/www.dbu.de\/en\/wp-json\/wp\/v2\/users\/2"}],"version-history":[{"count":18,"href":"https:\/\/www.dbu.de\/en\/wp-json\/wp\/v2\/termine\/29880\/revisions"}],"predecessor-version":[{"id":54178,"href":"https:\/\/www.dbu.de\/en\/wp-json\/wp\/v2\/termine\/29880\/revisions\/54178"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.dbu.de\/en\/wp-json\/wp\/v2\/media\/45526"}],"wp:attachment":[{"href":"https:\/\/www.dbu.de\/en\/wp-json\/wp\/v2\/media?parent=29880"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.dbu.de\/en\/wp-json\/wp\/v2\/categories?post=29880"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.dbu.de\/en\/wp-json\/wp\/v2\/tags?post=29880"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}