{"id":26758,"date":"2026-04-29T11:28:11","date_gmt":"2026-04-29T09:28:11","guid":{"rendered":"https:\/\/www.dbu.de\/projektdatenbank\/32480-01\/"},"modified":"2026-04-29T11:28:15","modified_gmt":"2026-04-29T09:28:15","slug":"32480-01","status":"publish","type":"projektdatenbank","link":"https:\/\/www.dbu.de\/en\/projektdatenbank\/32480-01\/","title":{"rendered":"Entwicklung und Erprobung von schulischen Umweltbildungsangeboten zum Thema Offshore-Windenergie"},"content":{"rendered":"<p>Zielsetzung und Anlass des Vorhabens<\/p>\n<p>\u00dcber die Offshore-Windenergie gibt es bisher kein p\u00e4dagogisches Material, insgesamt ist das Wissen in Deutschland \u00fcber die noch recht junge und aufwendige Technologieform begrenzt. Das Projekt soll Wissen schaffen sowie festigen und die zahlreichen Aspekte der Offshore-Windenergie beleuchten. Dabei sollen insbesondere kritische Themenfelder, wie Auswirkungen auf die Umwelt, auf den Tourismus, Stromgestehungskosten oder Netzausbau mit Sch\u00fcler\/innen aus den Sekundarstufen I und II erarbeitet werden. Sch\u00fcler\/innen als Nachfolgegeneration werden somit f\u00fcr das Thema Erneuerbare Energien, Klimaschutz und Nachhaltigkeit sensibilisiert.<\/p>\n<p>Darstellung der Arbeitsschritte und der angewandten Methoden<\/p>\n<p>In einem ersten Schritt wurden Begleit- und Ausstellungsmaterialien sowie Konzepte f\u00fcr die Durchf\u00fchrung von Schulworkshops und -wettbewerben erstellt. F\u00fcr die Begleitung und Evaluierung des Projektes wurde zu Projektbeginn ein unabh\u00e4ngiger Expertenbeirat gegr\u00fcndet. Die Konzepte wurden an ausgew\u00e4hlten Kooperationsschulen getestet. Die Bed\u00fcrfnisse der Schulen, der Lehrkr\u00e4fte und Sch\u00fcler wurden so bei der Konzeption besonders ber\u00fccksichtigt. Nach einer Evaluierung wurden Wettbewerbe und Workshops an Schulen, vornehmlich im Raum Niedersachsen und Bremen in den Schuljahren 2016\/17 und 2017\/18 durchgef\u00fchrt. Die Erfahrungen konnten bereits vor Projektende genutzt werden um, mit Unterst\u00fctzung der Gesellschaft f\u00fcr Energie und Klimaschutz Schleswig-Holstein (EKSH), weitere Wettbewerbe im Land Schleswig-Holstein durchzuf\u00fchren. Die Durchf\u00fchrung richtete sich streng an die Grunds\u00e4tze des Beutelsbacher Konsens.<\/p>\n<p>Ergebnisse und Diskussion<\/p>\n<p>Es konnten 1.023 Sch\u00fcler erreicht werden und damit deutlich mehr als im Projektantrag vorausgesagt. Die Steigerung betr\u00e4gt bei den Workshops knapp 50 Prozent und bei den Wettbewerben 30 Prozent, unter Einbeziehung der Wettbewerbe in Schleswig-Holstein gar bei \u00fcber 100 Prozent.<br \/>\nIn Zahlen konnten zus\u00e4tzliche 423 Sch\u00fcler, bzw. 70 Prozent mehr Sch\u00fcler erreicht werden.<br \/>\nAuch die Zahl der durchgef\u00fchrten Workshops f\u00e4llt mit 29 rund 60 Prozent gr\u00f6\u00dfer aus. Anstelle der vorausgesagten sechs bis zehn Wettbewerbe wurden 14 durchgef\u00fchrt \u2013 eine Steigerung von 40 bis 130 Prozent.<\/p>\n<p>\u00d6ffentlichkeitsarbeit und Pr\u00e4sentation<\/p>\n<p>Zu den Abschlussveranstaltungen und Ausfahrten wurden jeweils regionale Pressevertreter und lokale Politiker eingeladen und durch Pressemitteilungen informiert. Ende 2017 wurde vom RUZ Hollen und der Stiftung eine gemeinsame Pressekonferenz veranstaltet auf denen die Inhalte des Projekts thematisiert wurden. Auch der Newsletter der Stiftung OFFSHORE-WINDENERGIE sowie die Webseite der Stiftung verwiesen mehrfach auf das Projekt und die durchgef\u00fchrten Veranstaltungen.<br \/>\nDas Projekt wurde durch die Pr\u00e4sentation der Wanderausstellung im \u00f6ffentlichen Raum (Klimawoche, didacta, Er\u00f6ffnung Windpark \u201eSandbank\u201c, Gewerbeschau Fleisch &#038; Knolle, Tag der Erneuerbaren Energien Mecklenburg-Vorpommern) vielfach beworben und auch auf einer F\u00fclle von Branchenveranstaltungen (Offshore-Wind Summit Sassnitz, AGOW Konferenz \u201eZukunft Offshore\u201c, Nationale Maritime Konferenz, Kuratoriumssitzung Stiftung OFFSHORE-WINDENERGIE, Fachgruppe Aus- und Weiterbildung im Projekt MaWi-OWI, Studentenkonferenz \u201eCOOL\u201c der Fachhochschule Kiel) vorgestellt.<br \/>\nDie Wanderausstellung wird auch zuk\u00fcnftig Verwendung finden. Die Workshops sind weiterhin Teil des Kursangebots des Regionalen Umweltzentrum Hollen und k\u00f6nnen bei Bedarf auch an interessierte Schulen versendet werden.<\/p>\n<p>Fazit<\/p>\n<p>Das Projekt Offshore-Wind INSCHOOL: erarbeiten \u2013 verstehen \u2013 weitergeben konnte erfolgreich abgeschlossen werden. Sowohl die Zahl der erreichten Sch\u00fcler als auch die qualitative Bewertung von Lehrern und Sch\u00fclern zeigen, dass die Ziele des Projekts erreicht wurden.<br \/>\nAuch nach Projektabschluss und ohne weitere Ansprache gibt es eine gr\u00f6\u00dfere Anzahl von Schulen die Wettbewerbe und Workshops gern durchf\u00fchren w\u00fcrden. Das Thema Offshore-Wind als erneuerbare Energie stellt sich als bestens geeignet f\u00fcr die Integration in den Unterricht heraus.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Zielsetzung und Anlass des Vorhabens \u00dcber die Offshore-Windenergie gibt es bisher kein p\u00e4dagogisches Material, insgesamt ist das Wissen in Deutschland \u00fcber die noch recht junge und aufwendige Technologieform begrenzt. Das Projekt soll Wissen schaffen sowie festigen und die zahlreichen Aspekte der Offshore-Windenergie beleuchten. Dabei sollen insbesondere kritische Themenfelder, wie Auswirkungen auf die Umwelt, auf den [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"template":"","meta":{"footnotes":""},"categories":[],"tags":[47,64,51,52,2423,53],"class_list":["post-26758","projektdatenbank","type-projektdatenbank","status-publish","hentry","tag-klimaschutz","tag-niedersachsen","tag-ressourcenschonung","tag-umweltforschung","tag-umweltkommunikation","tag-umwelttechnik"],"meta_box":{"dbu_projektdatenbank_az_ges":"32480\/01","dbu_projektdatenbank_medien":"","dbu_projektdatenbank_pdfdatei":"","dbu_projektdatenbank_bsumme":"239.200,00","dbu_projektdatenbank_firma":"Stiftung der deutschen Wirtschaft f\u00fcr die Nutzung und\nErforschung der Windenergie auf See (Offshore-Stiftung)","dbu_projektdatenbank_strasse":"Oldenburger Str. 65","dbu_projektdatenbank_plz_str":"26316","dbu_projektdatenbank_ort_str":"Varel","dbu_projektdatenbank_p_von":"2015-12-08 00:00:00","dbu_projektdatenbank_p_bis":"2018-12-07 00:00:00","dbu_projektdatenbank_laufzeit":"2 Jahre und 12 Monate","dbu_projektdatenbank_telefon":"04451 9515 248","dbu_projektdatenbank_inet":"","dbu_projektdatenbank_bundesland":"Niedersachsen","dbu_projektdatenbank_foerderber":"130","dbu_projektdatenbank_ab_bericht":"DBU-Abschlussbericht-AZ-32480_01-Hauptbericht.pdf","dbu_projektdatenbank_ist_nachbewilligung_von":"","dbu_projektdatenbank_hat_nachbewilligung":"","dbu_headerimage_cover":"","dbu_submenu":"","dbu_submenu_position":"","dbu_submenu_entry":[]},"_links":{"self":[{"href":"https:\/\/www.dbu.de\/en\/wp-json\/wp\/v2\/projektdatenbank\/26758","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.dbu.de\/en\/wp-json\/wp\/v2\/projektdatenbank"}],"about":[{"href":"https:\/\/www.dbu.de\/en\/wp-json\/wp\/v2\/types\/projektdatenbank"}],"version-history":[{"count":2,"href":"https:\/\/www.dbu.de\/en\/wp-json\/wp\/v2\/projektdatenbank\/26758\/revisions"}],"predecessor-version":[{"id":43338,"href":"https:\/\/www.dbu.de\/en\/wp-json\/wp\/v2\/projektdatenbank\/26758\/revisions\/43338"}],"wp:attachment":[{"href":"https:\/\/www.dbu.de\/en\/wp-json\/wp\/v2\/media?parent=26758"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.dbu.de\/en\/wp-json\/wp\/v2\/categories?post=26758"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.dbu.de\/en\/wp-json\/wp\/v2\/tags?post=26758"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}