{"id":26671,"date":"2026-07-04T10:32:59","date_gmt":"2026-07-04T08:32:59","guid":{"rendered":"https:\/\/www.dbu.de\/projektdatenbank\/32587-01\/"},"modified":"2026-07-04T10:32:59","modified_gmt":"2026-07-04T08:32:59","slug":"32587-01","status":"publish","type":"projektdatenbank","link":"https:\/\/www.dbu.de\/en\/projektdatenbank\/32587-01\/","title":{"rendered":"Machbarkeitsstudie \u201eLebendiger Atlas &#8211; Natur Deutschland&#8221;"},"content":{"rendered":"<p>Zielsetzung und Anlass des Vorhabens<\/p>\n<p>F\u00fcr eine nachhaltige Entwicklung m\u00fcssen B\u00fcrgerinnen und B\u00fcrger in Entscheidungsprozesse, in die Durchf\u00fchrung<br \/>\nund die Evaluation des Schutzes und der nachhaltigen Nutzung der Naturg\u00fcter einbezogen werden.<br \/>\nCitizen Science bietet die Chance, durch Einbindung der B\u00fcrger Br\u00fccken zwischen Gesellschaft, Fl\u00e4chen-<br \/>\nManagement und Wissenschaft zu schlagen und zu nachhaltigen Transformationsprozessen in der Gesellschaft<br \/>\nbeizutragen. Der \u201aLebendige Atlas\u2018 soll einen \u00fcbergreifenden Baustein darstellen, um einerseits das<br \/>\nKapital und die Sch\u00f6nheit der Natur in Deutschland durch die B\u00fcrger zu erfassen, und andererseits Kapazit\u00e4ten<br \/>\nim Bereich Citizen Science zu entwickeln, zu b\u00fcndeln und zu st\u00e4rken. Zentrales Ziel ist ein Konzept zu<br \/>\neinem \u201aLebendiger Atlas\u2018 zur Anwendbarkeit und Vernetzung von bestehenden und geplanten Citizen Science-<br \/>\nAktivit\u00e4ten f\u00fcr die Erfassung und das Monitoring von Biodiversit\u00e4t und Kulturdenkm\u00e4lern. Die vorgesehene<br \/>\nMachbarkeitsstudie dient der Bestands- und Bedarfsanalyse zu Citizen Science in enger Kollaboration<br \/>\nvon Verb\u00e4nden, Fachgesellschaften und Wissenschaft.<\/p>\n<p>Darstellung der Arbeitsschritte und der angewandten Methoden<\/p>\n<p>F\u00fcr die Analyse wird eine \u00dcbersicht zu aktuellen Vorhaben zu diesen Themen im deutschen und internationalen<br \/>\nRaum erstellt und hinsichtlich verschiedener Erfolgskriterien untersucht, die den mitunter sehr unterschiedlichen<br \/>\nZielsetzungen und thematischen Anwendungsfeldern der Projekte entsprechen. Die daf\u00fcr n\u00f6tige<br \/>\nMachbarkeitsstudie soll in vier Arbeitspaketen erstellt werden: Arbeitspaket 1 beinhaltete die Gr\u00fcndung<br \/>\neines Projektrates mit assoziierten Partnern. In diesem Zusammenhang wurden ein Dialogforum mit Verb\u00e4nden,<br \/>\nFachgesellschaften, B\u00fcrgern und Vertretern aus Wissenschaft und Politik aufgebaut. Arbeitspaket 2<br \/>\nbestand aus mehreren Workshops f\u00fcr das Dialogforum zu den Themen Datenmanagement (inkl. Gutachten),<br \/>\nDatenrechte (inkl. Gutachten), Ehrenamt und Einbindung der Zivilgesellschaft, sowie zum m\u00f6glichen<br \/>\nFinanzierungskonzept. Arbeitspaket 3 widmete sich einer Bedarfs- und Bestandsanalyse im Bereich des<br \/>\nEhrenamtes sowie im Datenmanagement. Arbeitspaket 4 schlie\u00dflich bestand in der Konzepterstellung f\u00fcr<br \/>\neinen \u201aLebendigen Atlas \u2013 Natur Deutschland\u2018, wobei die vorangegangen Analysen und Ergebnisse der<br \/>\nWorkshops f\u00fcr ein Konzept f\u00fcr die Anwendung von Citizen Science f\u00fcr den Lebendigen Atlas genutzt wurden.<\/p>\n<p>Ergebnisse und Diskussion<\/p>\n<p>Die Machbarkeitsstudie zeigte, dass ein Vorhaben \u201eLebendiger Atlas &#8211; Natur Deutschland\u201c von den Akteuren<br \/>\nim Natur- und Umweltschutz als grunds\u00e4tzlich anstrebenswert und unter den weiteren Bedingungen auch als<br \/>\nrealisierbar eingesch\u00e4tzt wird. Dabei m\u00f6chten Fachgesellschaften, Umweltverb\u00e4nde und Partner aus der<br \/>\nWissenschaft einen Lebendigen Atlas gemeinsam gestalten.<br \/>\nEin Lebendiger Atlas kann in der Zusammenarbeit mit Beh\u00f6rden die bestehenden Strukturen der Fachbeh\u00f6rden<br \/>\nsinnvoll erg\u00e4nzen und sollte nicht parallele Systeme aufbauen. Die Machbarkeitsstudie zeigt, dass<br \/>\ndies von vielen Partnern erw\u00fcnscht und als m\u00f6glich erachtet wird. Dabei ist die Wertsch\u00e4tzung ehrenamtlicher<br \/>\nArbeit das A und O eines Lebendigen Atlas. Die Koordination von Freiwilligen sollte den Verb\u00e4nden und<br \/>\nFachgesellschaften bzw. einzelnen Projekten \u00fcberlassen bleiben. Eine kontinuierliche Zusammenarbeit zwischen<br \/>\nFachgesellschaften, Verb\u00e4nden, Wissenschaft und Fachbeh\u00f6rden sollte langfristig angelegt sein und<br \/>\nist zentral f\u00fcr den Erfolg und Impakt der gemeinsamen Arbeit. Eine Verbesserung der Erfassung von Umweltdaten<br \/>\nw\u00fcrde zudem durch eine beh\u00f6rdenseitig bessere Ausstattung gest\u00e4rkt, aber verlangt auch mehr<br \/>\nstaatliche Investitionen in das Management und die Qualifizierung von Freiwilligen, ohne dass staatliche<br \/>\nBeh\u00f6rden dies selbst direkt als Aufgabe wahrnehmen sollten. Der Lebendige Atlas sollte daher eng und<br \/>\nkomplement\u00e4r mit den Fachbeh\u00f6rden von Bund und L\u00e4ndern zusammenarbeiten. Dazu geh\u00f6rt vor allem die<br \/>\nenge Zusammenarbeit mit dem BfN, den bestehenden BfN-Monitoringprogrammen, der derzeitigen Entwicklung<br \/>\ndes Roten Liste Zentrums und den damit verbundenen Projekten.<br \/>\nDer Lebendige Atlas sollte auf einer Open Source\/ Open Access-Infrastruktur aufgebaut sein. Generelles<br \/>\nZiel ist eine Interoperabilit\u00e4t und Darstellung in einem gemeinsamen System, bei klarer Kenntlichmachung<br \/>\nder Datenqualit\u00e4t und Urheberschaft. Der Lebendige Atlas kann so Projekte und Fachgesellschaften darin<br \/>\nunterst\u00fctzen, ihre Daten eigenst\u00e4ndig nach anerkannten Qualit\u00e4tsstandards zu erfassen und aufzubereiten,<br \/>\nund er hat das Ziel, bestehende Initiativen zu verlinken. Gew\u00fcnscht sind eine qualitativ hochwertige kartographische<br \/>\nDarstellung sowie Auswertungsm\u00f6glichkeiten durch Verschneidung mit anderen Daten zur Umwelt.<br \/>\n\u00dcber die Bereitstellung und Nutzungsrechte der Daten sollten grunds\u00e4tzlich die Dateninhaber entscheiden.<br \/>\nVon vielen Ehrenamtlichen wurde bef\u00fcrwortet, dass Daten Open Access zu Verf\u00fcgung stehen. Die Begleitung<br \/>\ndurch den Lehrstuhl f\u00fcr B\u00fcrgerliches Recht, Wettbewerbs- und Immaterialg\u00fcterrecht, Medien- und Informationsrecht<br \/>\nder Universit\u00e4t G\u00f6ttingen kann eine Vertiefung und Anpassung der Ausarbeitung der rechtlichen<br \/>\nZusammenarbeit erm\u00f6glichen.<br \/>\nF\u00fcr die weitere Entwicklung bedarf es einer engen und vertrauensvollen Zusammenarbeit, wobei eine gute<br \/>\nGovernanz wie auch ein adaptives Management wichtig sind. Diese m\u00fcssen mit allen Partnern gemeinsam<br \/>\nerarbeitet und vereinbart sowie kontinuierlich durch einen Beirat begleitet werden.<br \/>\nIn der Machbarkeitsstudie wurde eine Vision \u201eLebendiger Atlas &#8211; Natur Deutschland\u201c mit 5 Kernpunkten<br \/>\nunter dem Motto \u201eForschen f\u00fcr Alle \u2013 Lebendiges Wissen schaffen\u201c mit Vertretern von Fachgesellschaften,<br \/>\nVerb\u00e4nden, Wissenschaft und Fachbeh\u00f6rden entwickelt:<br \/>\n\u2022 Projekte f\u00fcr Natur und Umwelt in Deutschland vernetzen und unterst\u00fctzen<br \/>\n\u2022 Daten zu Natur und Umwelt zusammenf\u00fchren, harmonisieren und visualisieren<br \/>\n\u2022 Umweltinformation und bestm\u00f6gliches Datenmanagement f\u00fcr Natur und Umwelt bereitstellen<br \/>\n\u2022 Menschen f\u00fcr Natur begeistern und Engagement erm\u00f6glichen<br \/>\n\u2022 Gemeinsam Wissen schaffen \u2013 Zukunft gestalten<\/p>\n<p>\u00d6ffentlichkeitsarbeit und Pr\u00e4sentation<\/p>\n<p>Die Machbarkeit lebte von der Bottom-Up Konzeption durch Workshops und Umfragen, sowie Diskussionen<br \/>\nauf Veranstaltungen der Partner und interessierter Fachbeh\u00f6rden, Organisationen und des BMUB.<br \/>\nEs wurde eine Webseite f\u00fcr die Bereitstellung aller Projektdokumente entwickelt<br \/>\nhttp:\/\/www.ufz.de\/lebendiger-atlas, sowie ein Flyer mit der Kurzinformation der Bedarfe und der Vision<\/p>\n<p>Fazit<\/p>\n<p>Ein Vorhaben \u201eLebendiger Atlas &#8211; Natur Deutschland\u201c wird von den Akteuren im Natur- und Umweltschutz<br \/>\nals grunds\u00e4tzlich anstrebenswert und auch als realisierbar eingesch\u00e4tzt. Eine Konzeption zu einem<br \/>\nmodularen Aufbau wurde entwickelt und sollte nun mit Fachbeh\u00f6rden weiter konkretisiert werden.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Zielsetzung und Anlass des Vorhabens F\u00fcr eine nachhaltige Entwicklung m\u00fcssen B\u00fcrgerinnen und B\u00fcrger in Entscheidungsprozesse, in die Durchf\u00fchrung und die Evaluation des Schutzes und der nachhaltigen Nutzung der Naturg\u00fcter einbezogen werden. Citizen Science bietet die Chance, durch Einbindung der B\u00fcrger Br\u00fccken zwischen Gesellschaft, Fl\u00e4chen- Management und Wissenschaft zu schlagen und zu nachhaltigen Transformationsprozessen in der [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"template":"","meta":{"footnotes":""},"categories":[],"tags":[47,2422,50,51,68,52],"class_list":["post-26671","projektdatenbank","type-projektdatenbank","status-publish","hentry","tag-klimaschutz","tag-landnutzung","tag-naturschutz","tag-ressourcenschonung","tag-sachsen","tag-umweltforschung"],"meta_box":{"dbu_projektdatenbank_az_ges":"32587\/01","dbu_projektdatenbank_medien":"","dbu_projektdatenbank_pdfdatei":"","dbu_projektdatenbank_bsumme":"112.887,00","dbu_projektdatenbank_firma":"Deutsches Zentrum f\u00fcr integrative\nBiodiversit\u00e4tsforschung (iDiv)\nim Helmholtz-Zentrum f\u00fcr Umweltforschung GmbH\n(UFZ) Halle-Jena-Leipzig\nMitglied des Wiss. Beirates der Bundesregierung","dbu_projektdatenbank_strasse":"Puschstr. 4","dbu_projektdatenbank_plz_str":"04103","dbu_projektdatenbank_ort_str":"Leipzig","dbu_projektdatenbank_p_von":"2015-09-01 00:00:00","dbu_projektdatenbank_p_bis":"2016-09-01 00:00:00","dbu_projektdatenbank_laufzeit":"1 Jahr","dbu_projektdatenbank_telefon":"0341-973 3153","dbu_projektdatenbank_inet":"","dbu_projektdatenbank_bundesland":"Sachsen","dbu_projektdatenbank_foerderber":"134","dbu_projektdatenbank_ab_bericht":"DBU-Abschlussbericht-AZ-32587.pdf","dbu_projektdatenbank_ist_nachbewilligung_von":"","dbu_projektdatenbank_hat_nachbewilligung":"","dbu_headerimage_cover":"","dbu_submenu":"","dbu_submenu_position":"","dbu_submenu_entry":[]},"_links":{"self":[{"href":"https:\/\/www.dbu.de\/en\/wp-json\/wp\/v2\/projektdatenbank\/26671","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.dbu.de\/en\/wp-json\/wp\/v2\/projektdatenbank"}],"about":[{"href":"https:\/\/www.dbu.de\/en\/wp-json\/wp\/v2\/types\/projektdatenbank"}],"version-history":[{"count":2,"href":"https:\/\/www.dbu.de\/en\/wp-json\/wp\/v2\/projektdatenbank\/26671\/revisions"}],"predecessor-version":[{"id":43350,"href":"https:\/\/www.dbu.de\/en\/wp-json\/wp\/v2\/projektdatenbank\/26671\/revisions\/43350"}],"wp:attachment":[{"href":"https:\/\/www.dbu.de\/en\/wp-json\/wp\/v2\/media?parent=26671"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.dbu.de\/en\/wp-json\/wp\/v2\/categories?post=26671"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.dbu.de\/en\/wp-json\/wp\/v2\/tags?post=26671"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}