{"id":26416,"date":"2026-07-04T10:32:49","date_gmt":"2026-07-04T08:32:49","guid":{"rendered":"https:\/\/www.dbu.de\/projektdatenbank\/31865-01\/"},"modified":"2026-07-04T10:32:49","modified_gmt":"2026-07-04T08:32:49","slug":"31865-01","status":"publish","type":"projektdatenbank","link":"https:\/\/www.dbu.de\/en\/projektdatenbank\/31865-01\/","title":{"rendered":"Innovative Untersuchungsmethoden zur nachhaltigen Wirksamkeit modellhafter Anoxia-Behandlung gegen Insektenbefall an national bedeutsamen Kulturg\u00fctern der Sammlungen der Stiftung Preu\u00dfischer Kulturbesitz"},"content":{"rendered":"<p>Zielsetzung und Anlass des Vorhabens<\/p>\n<p>Inhalte der anwendungsorientierten Forschungsarbeiten sind die modellhafte Methodik und neuartige Verfahren zur Umweltvertr\u00e4glichkeit und des ressourcenschonenden Substanzerhalts bei der nachhalti-gen Bewahrung national wertvoller Kulturg\u00fcter sowie eine innovative Technologie zur Diagnostik und Qualit\u00e4tssicherung bei Objektbehandlungen gegen Sch\u00e4dlingsbefall.<br \/>\nMuseale Sammlungen sind st\u00e4ndig der Gefahr ausgesetzt, biogene Sch\u00e4digungen zu erfahren. Unbe-achtet kann Sch\u00e4dlingsbefall einen Substanzverlust bis hin zur Zerst\u00f6rung der Objekte verursachen. Im Integrated Pest Management (IPM) gilt es Verfahren zur Vermeidung, der Fr\u00fcherkennung und einer ge-zielten Vernichtung materialsch\u00e4digender Organismen miteinander zu verbinden. Im Vordergrund stehen dabei physikalische und biologische Verfahren, die Schaderreger effizient und umweltschonend bek\u00e4mpfen. Bei prophylaktischen oder kurativen Behandlungen musealer Objekte gegen Sch\u00e4dlingsbefall sind Methoden wichtig, die besonders materialschonend und r\u00fcckstandsfrei durchgef\u00fchrt werden k\u00f6nnen. Diesen Anforderungen wird eine Anoxia-Behandlung mittels Stickstoffgas gerecht, wobei der verbleibende Sauerstoffanteil, das Umgebungsklima und die Behandlungsdauer den Erfolg der Ma\u00dfnahme beeinflussen. In Abh\u00e4ngigkeit von der Materialbeschaffenheit betroffener Objekte und den vorkommenden Sch\u00e4dlingsarten k\u00f6nnen die Behandlungszeit und die erforderliche Minimalkonzentration f\u00fcr Stickstoff sehr variabel sein. Im Projekt wurden die wirtschaftlich bedeutendsten Materialsch\u00e4dlinge in deren unterschiedlichen Entwicklungsstadien unter kontrollierten und im \u00fcblichen Museumsbetrieb reproduzierbaren Bedingungen mit Anoxia behandelt werden. Dabei wurden Dosis-Wirkungs-Parameter bei unterschiedlichen Klimabedingungen generiert. Zus\u00e4tzlich wurde die M\u00f6glichkeit einer zerst\u00f6rungsfreien Pr\u00fcfung durch Radarsensoren entwickelt und im Praxiseinsatz erprobt. Die Anwendung dieser Technologie kann dem Nachweis der Aktivit\u00e4t eines Befalls und der Erfolgskontrolle von Anoxia-Behandlungen dienen. In der technischen Ausf\u00fchrung als handliches Kleinger\u00e4t k\u00f6nnte UWB-Radardetektion von Sch\u00e4dlingsbefall Bestandteil von Routinearbeiten bei der Sammlungspflege werden<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Zielsetzung und Anlass des Vorhabens Inhalte der anwendungsorientierten Forschungsarbeiten sind die modellhafte Methodik und neuartige Verfahren zur Umweltvertr\u00e4glichkeit und des ressourcenschonenden Substanzerhalts bei der nachhalti-gen Bewahrung national wertvoller Kulturg\u00fcter sowie eine innovative Technologie zur Diagnostik und Qualit\u00e4tssicherung bei Objektbehandlungen gegen Sch\u00e4dlingsbefall. Museale Sammlungen sind st\u00e4ndig der Gefahr ausgesetzt, biogene Sch\u00e4digungen zu erfahren. Unbe-achtet kann Sch\u00e4dlingsbefall [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"template":"","meta":{"footnotes":""},"categories":[],"tags":[58,2423],"class_list":["post-26416","projektdatenbank","type-projektdatenbank","status-publish","hentry","tag-berlin","tag-umweltkommunikation"],"meta_box":{"dbu_projektdatenbank_az_ges":"31865\/01","dbu_projektdatenbank_medien":"","dbu_projektdatenbank_pdfdatei":"","dbu_projektdatenbank_bsumme":"215.530,00","dbu_projektdatenbank_firma":"Rathgen-Forschungslabor\nStaatliche Museen zu Berlin","dbu_projektdatenbank_strasse":"Schlossstr. 1 a","dbu_projektdatenbank_plz_str":"14059","dbu_projektdatenbank_ort_str":"Berlin","dbu_projektdatenbank_p_von":"2015-03-16 00:00:00","dbu_projektdatenbank_p_bis":"2017-11-30 00:00:00","dbu_projektdatenbank_laufzeit":"2 Jahre und 8 Monate","dbu_projektdatenbank_telefon":"030\/266427-120","dbu_projektdatenbank_inet":"www.smb.museum\/museen-und-einrichtungen\/rathgen-","dbu_projektdatenbank_bundesland":"Berlin","dbu_projektdatenbank_foerderber":"137","dbu_projektdatenbank_ab_bericht":"","dbu_projektdatenbank_ist_nachbewilligung_von":"","dbu_projektdatenbank_hat_nachbewilligung":"","dbu_headerimage_cover":"","dbu_submenu":"","dbu_submenu_position":"","dbu_submenu_entry":[]},"_links":{"self":[{"href":"https:\/\/www.dbu.de\/en\/wp-json\/wp\/v2\/projektdatenbank\/26416","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.dbu.de\/en\/wp-json\/wp\/v2\/projektdatenbank"}],"about":[{"href":"https:\/\/www.dbu.de\/en\/wp-json\/wp\/v2\/types\/projektdatenbank"}],"version-history":[{"count":1,"href":"https:\/\/www.dbu.de\/en\/wp-json\/wp\/v2\/projektdatenbank\/26416\/revisions"}],"predecessor-version":[{"id":39419,"href":"https:\/\/www.dbu.de\/en\/wp-json\/wp\/v2\/projektdatenbank\/26416\/revisions\/39419"}],"wp:attachment":[{"href":"https:\/\/www.dbu.de\/en\/wp-json\/wp\/v2\/media?parent=26416"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.dbu.de\/en\/wp-json\/wp\/v2\/categories?post=26416"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.dbu.de\/en\/wp-json\/wp\/v2\/tags?post=26416"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}