{"id":26387,"date":"2026-07-04T10:32:45","date_gmt":"2026-07-04T08:32:45","guid":{"rendered":"https:\/\/www.dbu.de\/projektdatenbank\/31759-01\/"},"modified":"2026-07-04T10:32:46","modified_gmt":"2026-07-04T08:32:46","slug":"31759-01","status":"publish","type":"projektdatenbank","link":"https:\/\/www.dbu.de\/en\/projektdatenbank\/31759-01\/","title":{"rendered":"Identifizierung von Mixed Tropical Hardwood (MTH) in Papier mittels chemotaxonomischer und morphologischer Merkmale"},"content":{"rendered":"<p>Zielsetzung und Anlass des Vorhabens<\/p>\n<p>Die Bedeutung von W\u00e4ldern generell und von Tropenw\u00e4ldern im Speziellen f\u00fcr die Umwelt ist existentiell. Dies gilt insbesondere im Hinblick auf Artenreichtum und Klima. Die Entwaldung wird als gr\u00f6\u00dfte Quelle anthropogener CO2-Emissionen gesehen. Zwei Drittel der an die Erdoberfl\u00e4che gebundenen Biodiversit\u00e4t wird den Tropenwald\u00f6kosystemen zugerechnet. <\/p>\n<p>Eine zentrale Rolle bei der Entwaldung wird dem illegalen Holzeinschlag zugeschrieben. Als Reaktion wird versucht, die Vermarktung von illegal gewonnenem Holz zu unterbinden. Die EU-Kommission hat deshalb 2003 einen Aktionsplan mit der Bezeichnung \u201eForest Law Enforcement, Governance and Tra-de\u201c(FLEGT) aufgelegt, der \u00fcber EU- Verordnungen und das EUTR (europ\u00e4ische Holzhandelssiche-rungsgesetzt) sowie das deutsche Holzhandelssicherungsgesetz in europ\u00e4isches und nationales Recht umgesetzt wird.<\/p>\n<p>Eine wichtige, zu kontrollierende Produktgruppe ist Papier. Die Bedeutung der verschiedenen Papiersorten ergibt sich aus den extrem hohen Produktionsmengen und der Tatsache, dass es sich bei Papieren um Produkte aus \u201ekomplexen Lieferketten\u201c handelt. F\u00fcr Produkte aus \u201ekomplexen Lieferketten\u201c, e-nem Begriff aus dem EUTR, ist die Einhaltung der durch die gesetzlichen Vorgaben vorgeschriebenen Sorgfaltspflichten nur schwer zu erreichen. Um den Marktteilnehmern mehr Sicherheit zu geben, ist die sichere Identifikation der f\u00fcr die Papierherstellung verwendeten Holzarten von gro\u00dfer Bedeutung. Weder Beh\u00f6rden noch Verbraucher k\u00f6nnen auf den Einsatz problematischer Holzarten im Papier reagieren, solange diese nicht zweifelsfrei nachgewiesen werden k\u00f6nnen. Die Ermittlung der f\u00fcr die Papierherstel-lung verwendeten Holzarten ist heute nur durch vergleichende Fasermikroskopie f\u00fcr konventionelle Zellstoffe mit Hilfe von Referenzfasern m\u00f6glich. Tropische Holzarten k\u00f6nnen mangels Referenzmaterialien und mangels spezifischer Merkmale bisher nicht eindeutig identifiziert werden. Eine eindeutige Identifikation der Fasern erfordert daher die Bereitstellung von belegtem Referenzmaterial und die Be-stimmung geeigneter Identifizierungsmerkmale. Dieses fehlt f\u00fcr MTH-Arten. Versch\u00e4rft wird die Situation in Zukunft durch die verst\u00e4rkte Nutzung der sogenannten \u201elesser known species\u201c, wodurch sich die Artenvielfalt in Zellstoff und Papier weiter erh\u00f6hen wird.<\/p>\n<p>Das Ziel des Projektes ist es, chemische und weitere morphologische Merkmale f\u00fcr die 23 im Vorg\u00e4n-gerprojekt untersuchten Gattungen\/Subgattungen und 5-10 weitere, als wichtig erachtete Gattungen herauszuarbeiten und f\u00fcr Identifizierungsprozesse zur Verf\u00fcgung zu stellen. Beide Ans\u00e4tze der Faseri-dentifizierung, chemisch und morphologisch, sollen verfolgt und kombiniert werden, um zuverl\u00e4ssigere Identifizierungen zu erm\u00f6glichen. <\/p>\n<p>Darstellung der Arbeitsschritte und der angewandten Methoden<\/p>\n<p>Das Ziel des Projektes wurde in neun Arbeitspaketen bearbeitet. Im ersten Arbeitspaket wurde f\u00fcr 5-10 neue Gattungen Material beschafft, um die erforderlichen Mazerate und gebleichten Referenzzellstoffe herzustellen, an denen die chemotaxonomischen und morphologischen Untersuchungen vorgenommen wurden. <\/p>\n<p>In den Arbeitspaketen 2 und 3 wurde die Methodik zur chemotaxonomischen Identifizierung von einzelnen Gattungen optimiert. Das Teilziel in diesen Paketen ist eine m\u00f6glichst vollst\u00e4ndige Erfassung aller chemischen Merkmale der einzelnen Gattungen. Zur Extraktion und Fraktionierung der chemischen Merkmale wurden Methoden wie \u201eAccelerated Solvent Extraction\u201c (ASE) und \u201eSolid Phase Extraction\u201c (SPE) genutzt. F\u00fcr eine optimale analytische Erfassung der chemischen Merkmale wurde die TD-GC\/MS den Extrakten und Fraktionen angepasst. Au\u00dferdem wurde die umfassende zweidimensionale Gaschromatographie (GCxGC) auf ihr Potenzial f\u00fcr die zu bearbeitenden Fragestellungen hin getestet. <\/p>\n<p>In dem Arbeitspaket 4 wurden alle 28 &#8211; 33 Gattungen chemotaxonomisch charakterisiert, und die Ergebnisse in einer Datenbank erfasst. <\/p>\n<p>In den Arbeitspaketen 5 und 6 wurden die Zellstofffasern morphologisch untersucht. Dabei wurden die morphologischen Merkmale sowohl mit dem Lichtmikroskop als auch mit dem Feldemissionsraster-elektronenmikroskop (FE-SEM) erfasst. Durch die h\u00f6here Aufl\u00f6sung des FE-SEM werden Erkennungsmerkmale sichtbar, die bisher nicht beschrieben sind. Die Ergebnisse beider Methoden wurden zur Erweiterung des bereits im Vorg\u00e4ngerprojekt erstellten Gef\u00e4\u00dfatlanten genutzt.<\/p>\n<p>In Arbeitspaket 7 wurde die nat\u00fcrliche Variabilit\u00e4t der chemischen und morphologischen Merkmale beispielhaft an einigen Gattungen untersucht. Die Betrachtung beider Merkmaltypen an einigen Gattungen erlaubt es, Synergieeffekte der Probenbeschaffung zu nutzen. Au\u00dferdem k\u00f6nnen die chemischen und morphologischen Merkmale der untersuchten Gattungen verzahnt und kombiniert werden. Die Idee ist, dass durch die Kombination beider Merkmaltypen Fragen zu Gattung, Art oder Herkunft einer Art bes-ser beantwortet werden k\u00f6nnen, als wenn die Ans\u00e4tze einzeln verfolgt werden.<\/p>\n<p>Im Arbeitspaket 8 wurden die im Projekt erworbenen Erkenntnisse zur Chemotaxonomie und Fasermor-phologie von MTH-Zellstoffen an Blind- und Praxisbeispielen von den beteiligten Projektpartnern angewendet.<\/p>\n<p>Das Arbeitspaket 9 umfasste die Dokumentation und Berichterstattung zum Verlauf des Projektes.<\/p>\n<p>Ergebnisse und Diskussion<\/p>\n<p>F\u00fcr beide in dem Projekt verfolgten Techniken, Anatomie und Chemotaxonomie, konnte der Umfang an Referenzmaterialien erweitert werden. Es stehen jetzt 31 sortenreine gebleichte Zellstoffe und 38 Mazerate relevanter, asiatischer H\u00f6lzer zur Verf\u00fcgung. Diese Referenzmaterialien wurden anatomisch cha-rakterisiert und die Ergebnisse in Form des \u201eAtlas of vessel elements\u201c (Helmling et al. 2018) den Marktteilnehmern zur Verf\u00fcgung gestellt. Neben einf\u00fchrenden Erkl\u00e4rungen zur mikroskopisch-anatomischen Identifizierung von Laubholzfaserstoffen an den Gef\u00e4\u00dfelementen, werden die charakteris-tischen Strukturmerkmale der einzelnen Gattungen\/Untergattungen eingehend beschrieben und mit mikroskopischen Bildern belegt. Damit wurden die Grundlagen geschaffen und der Allgemeinheit zur Verf\u00fcgung gestellt, diese Gattungen in Papieren zu identifizieren. <\/p>\n<p>Im Bereich der Chemotaxonomie musste ein hoher Aufwand bei der Methodenentwicklung geleistet werden. Die Mahlung unter Kryobedingungen und eine anschlie\u00dfende Soxtherm-Extraktion wurden als g\u00fcnstige Kombination zur Probenvorbereitung erachtet. Bei der anschlie\u00dfenden Analytik der Extrakte zeigte sich, dass das Trennverm\u00f6gen der 1D-GC in vielen F\u00e4llen nicht ausreicht, weshalb zus\u00e4tzliche Techniken wie Vortrennung mittels SPE und GCxGC-Messungen getestet wurden. W\u00e4hrend bei Fragen zur nat\u00fcrlichen Variabilit\u00e4t und Herkunftsfragen multivariate Auswertemethoden, wie die Hauptkomponentenanalyse, zum Einsatz kamen, wurde f\u00fcr die Identifizierung in Papier ein Datenbankansatz einge-setzt, um die hohe Anzahl an GC\/MS-Daten systematisch zu erfassen. Verschiedene Softwarepakete wurden hierf\u00fcr getestet. Die Software \u201eOpenchrom\u201c wurde als geeignet erachtet. Die Software ist rela-tiv neu, unter intensiver Entwicklung und muss f\u00fcr die Projektaufgaben allerdings noch besser adaptiert werden.<\/p>\n<p>Bei den Untersuchungen zur nat\u00fcrlichen Variabilit\u00e4t an 6 verschiedenen Proben der Gattung Gonystylus spp. und 14 Proben der Shorea Untergattung Rubroshorea erwiesen sich die entscheidenden mikroskopischen Merkmale im Falle der Gonystylus- und Rubroshorea-Proben als stabil. Die PCA-Auswertungen der GC\/MS-Daten ergaben deutliche systematische Unterschiede in den Zusammenset-zungen der sekund\u00e4ren Pflanzenstoffe der untersuchten Proben. Diese systematischen Unterschiede k\u00f6nnen vielleicht in Zukunft f\u00fcr tiefergehenden Identifizierungen genutzt werden. Die aktuellen Identifi-zierungen mittels Chemotaxonomie werden dadurch aber erst einmal erschwert.<\/p>\n<p>Die Gattung Gonystylus spp. chemotaxonomisch gezielt auch in niedrigen Anteilen in Mischungen mit industriell hergestelltem MTH zu identifizieren, ist bisher nur in Einzelf\u00e4llen gelungen. Ein Grund, dass dies noch nicht umfassend m\u00f6glich ist, wird in der nat\u00fcrlichen Variabilit\u00e4t der Zusammensetzung der sekund\u00e4ren Pflanzenstoffe innerhalb der Gattung vermutet.<\/p>\n<p>Abgeschlossen wurde das Projekt mit einem Blindversuch. Der Hochschule M\u00fcnchen wurden die vor-liegenden 31 Referenzzellstoffe zu Verf\u00fcgung gestellt mit der Aufgabe, 15 Pr\u00fcfbl\u00e4tter unbekannter Zusammensetzungen herzustellen. Die Zusammensetzungen wurde von den Partnerlaboren der TU Darmstadt und der ISEGA sowie dem TI mittels Mikroskopie auf Basis des Gef\u00e4\u00dfatlases ermittelt. Auf eine umfassende chemotaxonomische Bestimmung wurde verzichtet, da der Entwicklungsstand der Methodik als noch nicht ausreichend erachtet wurde. Im Rahmen des Blindtests waren 32&#215;15=480 Entscheidungen zu treffen. Es wurde von den drei Instituten eine hervorragende Trefferquote von 74 %, 92 % und 96 % erreicht. F\u00fcr die im Fokus der Untersuchung stehende Gattung Gonystylus und die mik-roskopisch-anatomisch \u00e4hnlichsten Gattungen Lophopetalum und Durio wurde eine Quote von 67 %, 100 % und 100 % erzielt. F\u00fcr das Projekt und insbesondere f\u00fcr den Faseratlas spricht, dass die besten Werte von einem \u201eexternen\u201c Institut erzielt wurden, das in die Herstellung und Untersuchung der Referenzstoffe nicht involviert war, und dem lediglich der Gef\u00e4\u00dfatlas als Grundlage f\u00fcr die Identifizierungen zur Verf\u00fcgung stand.<\/p>\n<p>So erfreulich die Mikroskopieergebnisse auch sind, muss ber\u00fccksichtigt werden, dass in realen Proben gr\u00f6\u00dfere Variationen, insbesondere durch weitere Holzarten enthalten sein k\u00f6nnen, f\u00fcr die noch keine Referenzen vorliegen und die auch eine hohe \u00c4hnlichkeit zu z. B. Gonystylus spp. aufweisen k\u00f6nnten. Aus diesem Grund und um m\u00f6glichst gerichtsfeste Aussagen zu erzielen, ist die Entwicklung einer von der Anatomie unabh\u00e4ngigen Methode wie der Chemotaxonomie von gro\u00dfer Bedeutung und sollte zusammen mit der Untersuchung zus\u00e4tzlicher Referenzmaterialien unbedingt weitergef\u00fchrt werden.<\/p>\n<p>\u00d6ffentlichkeitsarbeit und Pr\u00e4sentation<\/p>\n<p>Die Ergebnisse aus dem Projekt wurden vielf\u00e4ltig verbreitet:<\/p>\n<p>\u00d6ffentlichkeitsarbeit:<br \/>\n\u2022 Beim 3. \u201eHolzanatomischen Kolloquium\u201c am ihd in Dresden wurde ein Vortrag mit dem Titel \u201eIdentifizierung von Tropenh\u00f6lzern in Papier und Faserplatten\u201c gehalten.<br \/>\n\u2022 Au\u00dferdem wurde das Projekt bei der \u201eNacht des Wissens\u201c 2013, 2015 und 2017 in Hamburg<br \/>\n\u2022 Beim Branchentag des GD Holz in K\u00f6ln wurden Projektergebnisse vorgestellt.<\/p>\n<p>Ver\u00f6ffentlichungen:<br \/>\n\u2022 Helmling S, Olbrich A, Heinz I, Koch G (2018) Atlas of vessel elements \u2013 identification of Asian timbers. IAWA Journal 39 (3)<br \/>\n\u2022 Koch G, Haag V, Helmling S, Heinz I, Olbrich A (2017) Fasern im Fokus: Holzartenbestimmung von Faserplatten &#8211; Erfahrungen aus den Pr\u00fcfungen im Kontext der EUTR. MDF Mag Co: 86-88<br \/>\n\u2022 Helmling S, Olbrich A, Tepe L, Koch G (2016) Qualitative and quantitative characteristics of macerated vessels of 23 mixed tropical hardwood (MTH) species: a data collection for the iden-tification of wood species in pulp and paper. Holzforschung 70: 839-844<br \/>\n\u2022 Koch, G., Haag, V, Heinz, I., Richter, H.G. (2016): Die Europ\u00e4ische Holzhandelsverordnung (EUTR). Anforderungen an die Holzartenbestimmung in der Praxis. Holztechnologie 57(1), 5-11.<\/p>\n<p>Vortr\u00e4ge:<br \/>\n\u2022 Olbrich A (2017) Wood identification. BRC Timber Workshop, London, UK<br \/>\n\u2022 Olbrich A, Heinz I (2017) CITES-gesch\u00fctzte H\u00f6lzer in Zellstoff und Papier? Aufbau einer Daten-bank (Faseratlas) f\u00fcr die Bestimmungen von tropischen H\u00f6lzern in Papier. Informationsveranstaltung \u00fcber Anforderungen und Auswirkungen der neuen CITES-Listungen wichtiger Wirtschaftsbaumarten f\u00fcr die Holzverwendung und den Holzhandel \u2013 BfN und Th\u00fcnen Institut, Hamburg<br \/>\n\u2022 Olbrich A, Koch G (2017) Identifizierung von Tropenh\u00f6lzern in Papier mit holzanatomischen Methoden. Workshop &#8211; Illegalen Holzeinschlag eind\u00e4mmen DBU, Osnabr\u00fcck<br \/>\n\u2022 Odermatt J, Wassink A (2017) Identifizierung von Tropenh\u00f6lzern in Papier mit chemischen Methoden. Workshop &#8211; Illegalen Holzeinschlag eind\u00e4mmen DBU, Osnabr\u00fcck<br \/>\n\u2022 Olbrich A (2017) Wood identification. WWF GFTN-UK meeting, London, UK<br \/>\n\u2022 Olbrich A (2016) Artbestimmung in der Holzanatomie. FSC-Exkursion: Holzherk\u00fcnfte unter der Lupe, Gro\u00dfhansdorf<br \/>\n\u2022 Olbrich A (2016) Ist Tropenholz im Papier? Deutsche Aktionstage Nachhaltigkeit, Hamburg-Beim Journal \u201eHolzforschung\u201c wurde eine Publikation mit dem Titel \u201cQualitative and quantitative characteristics of macerated vessels of twenty-three mixed tropical hardwood (MTH) species: A data collection for identification of wood species in pulp and paper\u201d eingereicht.<br \/>\n\u2022 Koch, G., Haag, V, Heinz, I., Richter, H.G. (2016): Die Europ\u00e4ische Holzhandelsverordnung (EUTR). Anforderungen an die Holzartenbestimmung in der Praxis. Holztechnologie 57(1), 5-11.<br \/>\n\u2022 Weitere Vortr\u00e4ge und Ver\u00f6ffentlichungen werden folgen.<\/p>\n<p>Fazit<\/p>\n<p>Der im Projekt durchgef\u00fchrte Blindtest zeigt eindeutig, dass unbekannte Proben mit den durch das Projekt f\u00fcr die \u00d6ffentlichkeit zug\u00e4nglichen Referenzen verglichen werden und damit identifiziert werden k\u00f6nnen. Bei der Identifikation kann jedoch \u201enur\u201c mit der \u201ebesten\u201c \u00dcbereinstimmung zu den bestehenden Referenzen argumentiert werden. F\u00fcr einen gerichtsfesten Beweis, dass beispielsweise ein Papier unter anderem Holz der unter CITES-Schutz stehenden Gattung Gonystylus spp. enth\u00e4lt, ist deshalb unerl\u00e4sslich, eine von der Anatomie unabh\u00e4ngige Methode zu etablieren.<\/p>\n<p>Hier liegen die Hoffnungen auf der Chemotaxonomie. Das Projekt offenbarte allerdings den noch bestehenden Nachholbedarf der Chemotaxonomie im Hinblick auf die generelle Methodenentwicklung, wodurch der Informationsgehalt in den Chromatogrammen bisher nur teilweise genutzt werden kann. Die getesteten methodischen Varianten, bspw. 2D GC-HRMS sowie SPE zur Probenvorbereitung, ergaben vielversprechende Verbesserungsm\u00f6glichkeiten und die generellen \u201eFingerprinteigenschaften\u201c der Peakmuster in den Chromatogrammen erlauben vielleicht sogar Beitr\u00e4ge zur Erf\u00fcllung der Sorgfaltspflichten \u00fcber die klassische Identifizierung hinaus. Daher sollte die Chemotaxonomie als zu den bisherigen Ans\u00e4tzen alternative Herangehensweise unbedingt weiterverfolgt werden.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Zielsetzung und Anlass des Vorhabens Die Bedeutung von W\u00e4ldern generell und von Tropenw\u00e4ldern im Speziellen f\u00fcr die Umwelt ist existentiell. Dies gilt insbesondere im Hinblick auf Artenreichtum und Klima. Die Entwaldung wird als gr\u00f6\u00dfte Quelle anthropogener CO2-Emissionen gesehen. Zwei Drittel der an die Erdoberfl\u00e4che gebundenen Biodiversit\u00e4t wird den Tropenwald\u00f6kosystemen zugerechnet. Eine zentrale Rolle bei der [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"template":"","meta":{"footnotes":""},"categories":[],"tags":[61,47,51,52,53],"class_list":["post-26387","projektdatenbank","type-projektdatenbank","status-publish","hentry","tag-hamburg","tag-klimaschutz","tag-ressourcenschonung","tag-umweltforschung","tag-umwelttechnik"],"meta_box":{"dbu_projektdatenbank_az_ges":"31759\/01","dbu_projektdatenbank_medien":"","dbu_projektdatenbank_pdfdatei":"f415ab16.5391.4a40.9c0e.8487e4268bb5","dbu_projektdatenbank_bsumme":"275.319,00","dbu_projektdatenbank_firma":"Johann Heinrich von Th\u00fcnen-Institut (vTI)\nZentrum Holzwirtschaft\nArbeitsbereich chemische Holztechnologie","dbu_projektdatenbank_strasse":"Leuschnerstr. 91","dbu_projektdatenbank_plz_str":"21031","dbu_projektdatenbank_ort_str":"Hamburg","dbu_projektdatenbank_p_von":"2015-02-01 00:00:00","dbu_projektdatenbank_p_bis":"2017-09-30 00:00:00","dbu_projektdatenbank_laufzeit":"2 Jahre und 8 Monate","dbu_projektdatenbank_telefon":"49 40 73962528","dbu_projektdatenbank_inet":"www.holzwirtschaft.org","dbu_projektdatenbank_bundesland":"Hamburg","dbu_projektdatenbank_foerderber":"124","dbu_projektdatenbank_ab_bericht":"DBU-Abschlussbericht-AZ-31759.pdf","dbu_projektdatenbank_ist_nachbewilligung_von":"","dbu_projektdatenbank_hat_nachbewilligung":"","dbu_headerimage_cover":"","dbu_submenu":"","dbu_submenu_position":"","dbu_submenu_entry":[]},"_links":{"self":[{"href":"https:\/\/www.dbu.de\/en\/wp-json\/wp\/v2\/projektdatenbank\/26387","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.dbu.de\/en\/wp-json\/wp\/v2\/projektdatenbank"}],"about":[{"href":"https:\/\/www.dbu.de\/en\/wp-json\/wp\/v2\/types\/projektdatenbank"}],"version-history":[{"count":2,"href":"https:\/\/www.dbu.de\/en\/wp-json\/wp\/v2\/projektdatenbank\/26387\/revisions"}],"predecessor-version":[{"id":43280,"href":"https:\/\/www.dbu.de\/en\/wp-json\/wp\/v2\/projektdatenbank\/26387\/revisions\/43280"}],"wp:attachment":[{"href":"https:\/\/www.dbu.de\/en\/wp-json\/wp\/v2\/media?parent=26387"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.dbu.de\/en\/wp-json\/wp\/v2\/categories?post=26387"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.dbu.de\/en\/wp-json\/wp\/v2\/tags?post=26387"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}