{"id":26358,"date":"2026-07-04T10:32:41","date_gmt":"2026-07-04T08:32:41","guid":{"rendered":"https:\/\/www.dbu.de\/projektdatenbank\/31685-01\/"},"modified":"2026-07-04T10:32:44","modified_gmt":"2026-07-04T08:32:44","slug":"31685-01","status":"publish","type":"projektdatenbank","link":"https:\/\/www.dbu.de\/en\/projektdatenbank\/31685-01\/","title":{"rendered":"Neue Wege in der Forellenzucht &#8211; rein weibliche Best\u00e4nde mittels temperatursensibler Milchner (xx-V\u00e4ter)"},"content":{"rendered":"<p>Zielsetzung und Anlass des Vorhabens<\/p>\n<p>Mit dem Einsetzen der Geschlechtsreife und somit der Gonadenreifung, kommt es bei Forellen zu Einbu\u00dfen in der Leistung und der Produktqualit\u00e4t sowie erh\u00f6hten stress-, verletzungs- und krankheitsbedingten Verlusten. Da weibliche Tiere (Rogner) sp\u00e4ter geschlechtsreif werden, k\u00f6nnen sie auf h\u00f6here Gewichte ausgem\u00e4stet werden (Lachsforellen), ohne oben beschriebene Effekte in Kauf nehmen zu m\u00fcssen. Aus diesem Grund sind in der Regenbogenforellenzucht rein weibliche Best\u00e4nde gefragt, um wirtschaftlichen Aspekten sowie den hohen Qualit\u00e4tsanspr\u00fcchen des Verbrauchers gerecht zu werden. Das Ziel dieses Projektes war es daher, eine alternative Methode zur Erstellung rein weiblicher Best\u00e4nde zu erproben, die einerseits praktikabel ist und andererseits ohne den Einsatz von Hormonen auskommt. Dies ist insofern eine Herausforderung, als dass die Geschlechtsdeterminierung bei Forellen auf einem einfachen XY-System beruht. Es gibt jedoch Belege daf\u00fcr, dass auch \u00fcber die Erbr\u00fctungstemperatur unter bestimmten Bedingungen Einfluss auf das Geschlechterverh\u00e4ltnis genommen werden kann, was auch in eigenen Vorarbeiten der Arbeitsgruppe gezeigt werden konnte<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Zielsetzung und Anlass des Vorhabens Mit dem Einsetzen der Geschlechtsreife und somit der Gonadenreifung, kommt es bei Forellen zu Einbu\u00dfen in der Leistung und der Produktqualit\u00e4t sowie erh\u00f6hten stress-, verletzungs- und krankheitsbedingten Verlusten. Da weibliche Tiere (Rogner) sp\u00e4ter geschlechtsreif werden, k\u00f6nnen sie auf h\u00f6here Gewichte ausgem\u00e4stet werden (Lachsforellen), ohne oben beschriebene Effekte in Kauf nehmen [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"template":"","meta":{"footnotes":""},"categories":[],"tags":[64],"class_list":["post-26358","projektdatenbank","type-projektdatenbank","status-publish","hentry","tag-niedersachsen"],"meta_box":{"dbu_projektdatenbank_az_ges":"31685\/01","dbu_projektdatenbank_medien":"","dbu_projektdatenbank_pdfdatei":"","dbu_projektdatenbank_bsumme":"119.500,00","dbu_projektdatenbank_firma":"Georg-August-Universit\u00e4t G\u00f6ttingen\nAbt. Aquakultur und Gew\u00e4sser\u00f6kologie\nDepartment f\u00fcr Nutztierwissenschaften","dbu_projektdatenbank_strasse":"Albrecht-Thaer-Weg 3","dbu_projektdatenbank_plz_str":"37075","dbu_projektdatenbank_ort_str":"G\u00f6ttingen","dbu_projektdatenbank_p_von":"2014-10-01 00:00:00","dbu_projektdatenbank_p_bis":"2018-06-30 00:00:00","dbu_projektdatenbank_laufzeit":"3 Jahre und 9 Monate","dbu_projektdatenbank_telefon":"05 51\/39 56-07","dbu_projektdatenbank_inet":"www.uni-goettingen.de","dbu_projektdatenbank_bundesland":"Niedersachsen","dbu_projektdatenbank_foerderber":"123","dbu_projektdatenbank_ab_bericht":"DBU-Abschlussbericht-AZ-31685_01-Hauptbericht.pdf","dbu_projektdatenbank_ist_nachbewilligung_von":"","dbu_projektdatenbank_hat_nachbewilligung":"","dbu_headerimage_cover":"","dbu_submenu":"","dbu_submenu_position":"","dbu_submenu_entry":[]},"_links":{"self":[{"href":"https:\/\/www.dbu.de\/en\/wp-json\/wp\/v2\/projektdatenbank\/26358","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.dbu.de\/en\/wp-json\/wp\/v2\/projektdatenbank"}],"about":[{"href":"https:\/\/www.dbu.de\/en\/wp-json\/wp\/v2\/types\/projektdatenbank"}],"version-history":[{"count":1,"href":"https:\/\/www.dbu.de\/en\/wp-json\/wp\/v2\/projektdatenbank\/26358\/revisions"}],"predecessor-version":[{"id":39361,"href":"https:\/\/www.dbu.de\/en\/wp-json\/wp\/v2\/projektdatenbank\/26358\/revisions\/39361"}],"wp:attachment":[{"href":"https:\/\/www.dbu.de\/en\/wp-json\/wp\/v2\/media?parent=26358"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.dbu.de\/en\/wp-json\/wp\/v2\/categories?post=26358"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.dbu.de\/en\/wp-json\/wp\/v2\/tags?post=26358"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}