{"id":26355,"date":"2026-07-04T10:32:24","date_gmt":"2026-07-04T08:32:24","guid":{"rendered":"https:\/\/www.dbu.de\/projektdatenbank\/29349-02\/"},"modified":"2026-07-04T10:32:26","modified_gmt":"2026-07-04T08:32:26","slug":"29349-02","status":"publish","type":"projektdatenbank","link":"https:\/\/www.dbu.de\/en\/projektdatenbank\/29349-02\/","title":{"rendered":"Entwicklung einer innovativen Trennmethode f\u00fcr gebrauchte Bentonitsuspensionen zur \u00f6konomisch vorteilhaften, ressourcenschonenden und umweltgerechten Entsorgung (2. Phase)"},"content":{"rendered":"<p>Zielsetzung und Anlass des Vorhabens<\/p>\n<p>Bentonite sind aufbereitete Tone aus nat\u00fcrlichen Vorkommen, die in Wasser dispergiert f\u00fcr den Spezial-tiefbau von besonderer baupraktischer Bedeutung sind. Durch die vielseitige Verwendbarkeit entstehen auf diversen Baustellen gro\u00dfe Mengen von gebrauchten Bentonitsuspensionen, die durch Aufladung mit Bodenpartikeln ihre bautechnisch relevanten Eigenschaften verlieren und in dieser Form nicht mehr ver-wendet werden k\u00f6nnen. Die anschlie\u00dfende Entsorgung der gebrauchten Bentonitsuspensionen erweist sich als schwierig, da diese stabil sind und sich nicht selbstst\u00e4ndig entmischen.<br \/>\nHier setzte die Idee eines geschlossenen Recyclingprozesses f\u00fcr Bentonitsuspensionen an: Ziel dieser Forschungsarbeit war und ist es, die aktuell bestehenden Separationsverfahren durch ein innovatives, neuartiges Verfahren zu optimieren oder zu ersetzen und in ein neu zu entwickelndes Aufbereitungssys-tem einzubinden. Synergie-Effekte mit den bestehenden Systemen leisten dabei einen positiven Beitrag zur Entlastung der vorrangigen Kosten und der Umwelt, indem die Ressourcen der Bentonitlagerst\u00e4tten und Wasservorkommen geschont sowie Transportwege massiv reduziert werden.<br \/>\nDas Entwicklungsziel konzentrierte sich auf die Anwendung der Elektrokoagulationstechnik zur Trennung von Bentonitsuspensionen, die mit Bodenpartikeln bis an die Grenze der Tragf\u00e4higkeit aufgeladen sind. Hierbei wurden v\u00f6llig neue Anforderungen an die Trenntechnik gestellt, da die Schwebstoffe, die in der kommunalen oder industriellen Abwasserreinigung zu separieren sind, in weitaus geringeren Konzentra-tionen anfallen und mit den Inhaltsstoffen von aufgeladenen Bentonitsuspensionen nicht vergleichbar sind.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Zielsetzung und Anlass des Vorhabens Bentonite sind aufbereitete Tone aus nat\u00fcrlichen Vorkommen, die in Wasser dispergiert f\u00fcr den Spezial-tiefbau von besonderer baupraktischer Bedeutung sind. Durch die vielseitige Verwendbarkeit entstehen auf diversen Baustellen gro\u00dfe Mengen von gebrauchten Bentonitsuspensionen, die durch Aufladung mit Bodenpartikeln ihre bautechnisch relevanten Eigenschaften verlieren und in dieser Form nicht mehr ver-wendet werden [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"template":"","meta":{"footnotes":""},"categories":[],"tags":[47,65,51,52,53],"class_list":["post-26355","projektdatenbank","type-projektdatenbank","status-publish","hentry","tag-klimaschutz","tag-nordrhein-westfalen","tag-ressourcenschonung","tag-umweltforschung","tag-umwelttechnik"],"meta_box":{"dbu_projektdatenbank_az_ges":"29349\/02","dbu_projektdatenbank_medien":"","dbu_projektdatenbank_pdfdatei":"","dbu_projektdatenbank_bsumme":"399.693,00","dbu_projektdatenbank_firma":"MSE Filterpressen GmbH","dbu_projektdatenbank_strasse":"Am Eisengraben 3","dbu_projektdatenbank_plz_str":"75196","dbu_projektdatenbank_ort_str":"Remchingen","dbu_projektdatenbank_p_von":"2015-01-01 00:00:00","dbu_projektdatenbank_p_bis":"2018-12-31 00:00:00","dbu_projektdatenbank_laufzeit":"3 Jahre und 12 Monate","dbu_projektdatenbank_telefon":"07232\/3650-0","dbu_projektdatenbank_inet":"","dbu_projektdatenbank_bundesland":"Nordrhein-Westfalen","dbu_projektdatenbank_foerderber":"115","dbu_projektdatenbank_ab_bericht":"DBU-Abschlussbericht-AZ-29349_02-Hauptbericht.pdf","dbu_projektdatenbank_ist_nachbewilligung_von":"","dbu_projektdatenbank_hat_nachbewilligung":"","dbu_headerimage_cover":"","dbu_submenu":"","dbu_submenu_position":"","dbu_submenu_entry":[]},"_links":{"self":[{"href":"https:\/\/www.dbu.de\/en\/wp-json\/wp\/v2\/projektdatenbank\/26355","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.dbu.de\/en\/wp-json\/wp\/v2\/projektdatenbank"}],"about":[{"href":"https:\/\/www.dbu.de\/en\/wp-json\/wp\/v2\/types\/projektdatenbank"}],"version-history":[{"count":1,"href":"https:\/\/www.dbu.de\/en\/wp-json\/wp\/v2\/projektdatenbank\/26355\/revisions"}],"predecessor-version":[{"id":39358,"href":"https:\/\/www.dbu.de\/en\/wp-json\/wp\/v2\/projektdatenbank\/26355\/revisions\/39358"}],"wp:attachment":[{"href":"https:\/\/www.dbu.de\/en\/wp-json\/wp\/v2\/media?parent=26355"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.dbu.de\/en\/wp-json\/wp\/v2\/categories?post=26355"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.dbu.de\/en\/wp-json\/wp\/v2\/tags?post=26355"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}