{"id":25861,"date":"2026-07-04T10:32:24","date_gmt":"2026-07-04T08:32:24","guid":{"rendered":"https:\/\/www.dbu.de\/projektdatenbank\/29770-01\/"},"modified":"2026-07-04T10:32:28","modified_gmt":"2026-07-04T08:32:28","slug":"29770-01","status":"publish","type":"projektdatenbank","link":"https:\/\/www.dbu.de\/en\/projektdatenbank\/29770-01\/","title":{"rendered":"G\u00e4rten f\u00fcr die Zukunft &#8211; ein Bildungsprojekt zur F\u00f6rderung von Nachhaltigkeit in der beruflichen Bildung und in Privathaushalten in den Themenfeldern G\u00e4rtnern und Ern\u00e4hrung"},"content":{"rendered":"<p>Zielsetzung und Anlass des Vorhabens<\/p>\n<p>Ziel des Projektes ist es, anhand von Modellg\u00e4rten und Workshops aufzuzeigen, wie wir den Wasserverbrauch senken, auf k\u00fcnstlichen Stickstoffd\u00fcnger verzichten und Stoffkreisl\u00e4ufe sichtbar machen k\u00f6nnen. Im Rahmen des Bildungsprojektes \u201eG\u00e4rten f\u00fcr die Zukunft\u201c wurden insgesamt vier G\u00e4rten aufgebaut. Hauptzielgruppen waren Kinder, Jugendliche und junge Erwachsene. Ein besonderer Fokus wurde hierbei auf die Integration von Menschen mit Migrationshintergrund bzw. Menschen aus sozialen Brennpunkten gelegt. Um m\u00f6glichst viele verschiedene Zielgruppen zu erreichen, wurden die G\u00e4rten im Umfeld eines gro\u00dfen Neubaugebietes, einer Schule und einer Kleingartenanlage entwickelt. Parallel fanden Workshops in den G\u00e4rten mit einer Vielfalt an Akteuren und in Zusammenarbeit mit der Berufs- und der Hochschulbildung statt. Die Modellg\u00e4rten sollen auch in Zukunft als Gemeinschafts- und Demonstrationsg\u00e4rten f\u00fcr nachhaltiges G\u00e4rtnern und nachhaltigen Konsum fungieren<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Zielsetzung und Anlass des Vorhabens Ziel des Projektes ist es, anhand von Modellg\u00e4rten und Workshops aufzuzeigen, wie wir den Wasserverbrauch senken, auf k\u00fcnstlichen Stickstoffd\u00fcnger verzichten und Stoffkreisl\u00e4ufe sichtbar machen k\u00f6nnen. Im Rahmen des Bildungsprojektes \u201eG\u00e4rten f\u00fcr die Zukunft\u201c wurden insgesamt vier G\u00e4rten aufgebaut. Hauptzielgruppen waren Kinder, Jugendliche und junge Erwachsene. Ein besonderer Fokus wurde hierbei [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"template":"","meta":{"footnotes":""},"categories":[],"tags":[2422,64,2423],"class_list":["post-25861","projektdatenbank","type-projektdatenbank","status-publish","hentry","tag-landnutzung","tag-niedersachsen","tag-umweltkommunikation"],"meta_box":{"dbu_projektdatenbank_az_ges":"29770\/01","dbu_projektdatenbank_medien":"","dbu_projektdatenbank_pdfdatei":"","dbu_projektdatenbank_bsumme":"124.840,00","dbu_projektdatenbank_firma":"Deutsche Umwelthilfe e. V. (DUH)\nBundesgesch\u00e4ftsstelle Hannover\/\nRegionalverband Nord","dbu_projektdatenbank_strasse":"Goebenstr. 3 a","dbu_projektdatenbank_plz_str":"30161","dbu_projektdatenbank_ort_str":"Hannover","dbu_projektdatenbank_p_von":"2013-10-15 00:00:00","dbu_projektdatenbank_p_bis":"2017-03-31 00:00:00","dbu_projektdatenbank_laufzeit":"3 Jahre und 6 Monate","dbu_projektdatenbank_telefon":"0511 \/ 390 805 14","dbu_projektdatenbank_inet":"","dbu_projektdatenbank_bundesland":"Niedersachsen","dbu_projektdatenbank_foerderber":"135","dbu_projektdatenbank_ab_bericht":"DBU-Abschlussbericht-AZ-29770.pdf","dbu_projektdatenbank_ist_nachbewilligung_von":"","dbu_projektdatenbank_hat_nachbewilligung":"","dbu_headerimage_cover":"","dbu_submenu":"","dbu_submenu_position":"","dbu_submenu_entry":[]},"_links":{"self":[{"href":"https:\/\/www.dbu.de\/en\/wp-json\/wp\/v2\/projektdatenbank\/25861","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.dbu.de\/en\/wp-json\/wp\/v2\/projektdatenbank"}],"about":[{"href":"https:\/\/www.dbu.de\/en\/wp-json\/wp\/v2\/types\/projektdatenbank"}],"version-history":[{"count":2,"href":"https:\/\/www.dbu.de\/en\/wp-json\/wp\/v2\/projektdatenbank\/25861\/revisions"}],"predecessor-version":[{"id":43197,"href":"https:\/\/www.dbu.de\/en\/wp-json\/wp\/v2\/projektdatenbank\/25861\/revisions\/43197"}],"wp:attachment":[{"href":"https:\/\/www.dbu.de\/en\/wp-json\/wp\/v2\/media?parent=25861"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.dbu.de\/en\/wp-json\/wp\/v2\/categories?post=25861"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.dbu.de\/en\/wp-json\/wp\/v2\/tags?post=25861"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}