{"id":25408,"date":"2026-04-29T11:20:02","date_gmt":"2026-04-29T09:20:02","guid":{"rendered":"https:\/\/www.dbu.de\/projektdatenbank\/28177-01\/"},"modified":"2026-04-29T11:20:05","modified_gmt":"2026-04-29T09:20:05","slug":"28177-01","status":"publish","type":"projektdatenbank","link":"https:\/\/www.dbu.de\/en\/projektdatenbank\/28177-01\/","title":{"rendered":"F\u00f6rderinitiative Aquakultur: Hormonfreie Tilapiaproduktion sichert nachhaltige Fischproduktion in Deutschland"},"content":{"rendered":"<p>Zielsetzung und Anlass des Vorhabens<\/p>\n<p>Viele der in Aquakultur kultivierten Fischarten weisen einen starken Geschlechtsdimorphismus auf. Um das Geschlecht der Fische zu beeinflussen, werden in vielen L\u00e4ndern synthetische Hormone eingesetzt. Diese werden den Fischen w\u00e4hrend der Geschlechtsdifferenzierung verabreicht. Besonders weit verbreitet ist dieses Vorgehen bei der Produktion von Niltilapien, wobei hier die m\u00e4nnlichen Tiere schneller wachsen und daher bevorzugt werden. Die Umweltrelevanz und Konsumentenakzeptanz dieses Verfahrens bedingen bei steigender Nachfrage und wachsenden Importmengen in der EU nachhaltigere Protokolle zur Erstellung rein-m\u00e4nnlicher Populationen. Daher war das prim\u00e4re Ziel dieses Vorhabens eine hormonfreie Setzlingsproduktion von Tilapien in Deutschland zu erm\u00f6glichen.<\/p>\n<p>Darstellung der Arbeitsschritte und der angewandten Methoden<\/p>\n<p>In zwei Versuchsdurchg\u00e4ngen wurden temperaturbehandelte ph\u00e4notypische M\u00e4nnchen (TPM), genetische M\u00e4nnchen (GM) und hormonbehandelte ph\u00e4notypische M\u00e4nnchen (HPM) hinsichtlich ihrer Mastleistungen und Schlachtk\u00f6rperparameter verglichen. Diese Mastleistungspr\u00fcfung wurde in der Kreislaufanlage der Fisch und Wasser GmbH in Oelzschau unter kommerziellen Bedingungen durchgef\u00fchrt. Die Besatzfische der einzelnen Mastdurchg\u00e4nge wurden in der Warmwasserkreislaufanlage der Abteilung Aquakultur und Gew\u00e4sser\u00f6kologie der Georg-August-Universit\u00e4t erstellt, aufgezogen und zur anschlie\u00dfenden Ausmast zum Kooperationspartner gebracht. Anschlie\u00dfend erfolgte in der Abteilung Aquakultur und Gew\u00e4sser\u00f6kologie die statistische Auswertung der Wachstumsleistungen und Schlachtk\u00f6rperparameter f\u00fcr die verschiedenen Pr\u00fcfgruppen. Neben den Mastversuchen wurde der Prototyp einer Reproduktionseinheit f\u00fcr Tilapien entwickelt. Langfristig soll auf diesem Weg eine Setzlingsproduktion erm\u00f6glicht werden, bei der mit Hilfe einer Temperaturbehandlung rein m\u00e4nnliche Besatzfische f\u00fcr eine anschlie\u00dfende Mast produziert werden k\u00f6nnen.<\/p>\n<p>Ergebnisse und Diskussion<\/p>\n<p>In der vorliegenden Untersuchung wurden zun\u00e4chst genetische (XY) mit TPM (XX) und in einem zweiten Mastdurchgang GM (XY), TPM (XX\/XY) und HPM (XX\/XY) miteinander verglichen. Die TPM Tilapien zeigten in beiden Versuchsreihen vergleichbare, bei separater Haltung sogar bessere Mastleistungen als GM und HPM. In der zweiten Versuchsreihe k\u00f6nnten aufgrund des communal testings soziale Interaktionen zwischen den Tieren ausschlaggebend f\u00fcr das bessere Abwachsen der GM sein. Allerdings k\u00f6nnten ebenso genetische Unterschiede aufgrund der Tatsache, dass nicht die gleichen Elterntiere genutzt wurden, eine Rolle spielen. Nichtsdestotrotz zeigte sich in der zweiten Versuchsreihe deutlich ein negativer Effekt der Hormonbehandlung auf die Wachstumsleistung. Bei gleicher Genetik und gleicher Umwelt (communal testing) wuchsen TPM signifikant besser und wiesen zudem vergleichbare Schlachtk\u00f6rperparameter auf. Es ist daher anzunehmen, dass TPM Tilapien den aufgrund ihrer W\u00e4rmebehandlung erzielten Wachstumsvorsprung gegen\u00fcber den genetischen M\u00e4nnchen \u00fcber die gesamte Wachstumsperiode halten, bzw. sogar ausbauen k\u00f6nnen.<br \/>\nDie vorliegenden Reproduktionsversuche best\u00e4tigten die M\u00f6glichkeit einer r\u00e4umlichen Trennung zwischen m\u00e4nnlichen und weiblichen Tilapien sowie eine Unterteilung des Beckens in verschiedene Funktionsbereiche. Es zeigte sich, dass die Weibchen die Laichboxen der M\u00e4nnchen f\u00fcr die Reproduktion annehmen. M\u00e4nnliche Tiere konnten in der Box ihr normales Verhalten aus\u00fcben und standen nicht unter dem Stress, mit Artgenossen Rangk\u00e4mpfe auszuf\u00fchren oder ihr Territorium verteidigen zu m\u00fcssen. In allen Versuchsreihen zur Testung der Reproduktionsleistung im Tilapia Breeding Center konnten erfolgreiche Laichereignisse mit befruchteten Eiern festgestellt werden. Die Ergebnisse des Tilapia Breeding Center zeigten jedoch auch, dass das Verfahren f\u00fcr eine effiziente Setzlingsproduktion noch weiter optimiert werden muss. Das Prinzip des Tilapia Breeding Centers als solches funktionierte gut, allerdings m\u00fcssen die Reproduktionsleistungen der Weibchen noch verbessert werden.<\/p>\n<p>\u00d6ffentlichkeitsarbeit und Pr\u00e4sentation<\/p>\n<p>Eine Pr\u00e4sentation des Projekts Hormonfreie Tilapiaproduktion sichert nachhaltige Fischproduktion in Deutschland erfolgte auf dem DBU-Workshop am 8. und 9. Juli im ZUK der DBU. Des Weiteren erhielt das Projekt die M\u00f6glichkeit vom Ministerium f\u00fcr Wissenschaft und Kultur des Landes Niedersachen auf dem Nieders\u00e4chsischen Gemeinschaftsstand im Rahmen der Hannover Messe 2012 (23.04.-27.04.) pr\u00e4sentiert zu werden. Anhand des Funktionsmodells des TBC konnte den Besuchern die Funktion und Notwendigkeit der Entwicklung einer solchen Erbr\u00fctungseinheit n\u00e4her gebracht werden.<\/p>\n<p>Fazit<\/p>\n<p>Es konnte gezeigt werden, dass temperaturbehandelte, ph\u00e4notypisch m\u00e4nnliche Tilapien einen Wachstumsvorteil gegen\u00fcber hormonbehandelten M\u00e4nnchen aufweisen. Bessere Schlachtparameter der temperaturbehandelten ph\u00e4notypischen M\u00e4nnchen sprachen au\u00dferdem f\u00fcr die Nutzung dieser Tiere in der Aquakultur. Eine effiziente Setzlingsproduktion im Tilapia Breeding Centre ist derzeit noch nicht gegeben. Das Prinzip des Tilapia Breeding Centres als solches funktionierte gut, allerdings m\u00fcssen die Verfahren zur Steigerung der Reproduktionsleistungen der Rogner weiter optimiert werden.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Zielsetzung und Anlass des Vorhabens Viele der in Aquakultur kultivierten Fischarten weisen einen starken Geschlechtsdimorphismus auf. Um das Geschlecht der Fische zu beeinflussen, werden in vielen L\u00e4ndern synthetische Hormone eingesetzt. Diese werden den Fischen w\u00e4hrend der Geschlechtsdifferenzierung verabreicht. Besonders weit verbreitet ist dieses Vorgehen bei der Produktion von Niltilapien, wobei hier die m\u00e4nnlichen Tiere schneller [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"template":"","meta":{"footnotes":""},"categories":[],"tags":[64,53],"class_list":["post-25408","projektdatenbank","type-projektdatenbank","status-publish","hentry","tag-niedersachsen","tag-umwelttechnik"],"meta_box":{"dbu_projektdatenbank_az_ges":"28177\/01","dbu_projektdatenbank_medien":"","dbu_projektdatenbank_pdfdatei":"A-28177.pdf","dbu_projektdatenbank_bsumme":"209.000,00","dbu_projektdatenbank_firma":"Georg-August-Universit\u00e4t G\u00f6ttingen\nAbt. Aquakultur und Gew\u00e4sser\u00f6kologie\nDepartment f\u00fcr Nutztierwissenschaften","dbu_projektdatenbank_strasse":"Albrecht-Thaer-Weg 3","dbu_projektdatenbank_plz_str":"37075","dbu_projektdatenbank_ort_str":"G\u00f6ttingen","dbu_projektdatenbank_p_von":"2010-10-01 00:00:00","dbu_projektdatenbank_p_bis":"2012-03-31 00:00:00","dbu_projektdatenbank_laufzeit":"1 Jahr und 6 Monate","dbu_projektdatenbank_telefon":"05 51\/39 56-07","dbu_projektdatenbank_inet":"www.uni-goettingen.de","dbu_projektdatenbank_bundesland":"Niedersachsen","dbu_projektdatenbank_foerderber":"121","dbu_projektdatenbank_ab_bericht":"DBU-Abschlussbericht-AZ-28177.pdf","dbu_projektdatenbank_ist_nachbewilligung_von":"","dbu_projektdatenbank_hat_nachbewilligung":"","dbu_headerimage_cover":"","dbu_submenu":"","dbu_submenu_position":"","dbu_submenu_entry":[]},"_links":{"self":[{"href":"https:\/\/www.dbu.de\/en\/wp-json\/wp\/v2\/projektdatenbank\/25408","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.dbu.de\/en\/wp-json\/wp\/v2\/projektdatenbank"}],"about":[{"href":"https:\/\/www.dbu.de\/en\/wp-json\/wp\/v2\/types\/projektdatenbank"}],"version-history":[{"count":1,"href":"https:\/\/www.dbu.de\/en\/wp-json\/wp\/v2\/projektdatenbank\/25408\/revisions"}],"predecessor-version":[{"id":38411,"href":"https:\/\/www.dbu.de\/en\/wp-json\/wp\/v2\/projektdatenbank\/25408\/revisions\/38411"}],"wp:attachment":[{"href":"https:\/\/www.dbu.de\/en\/wp-json\/wp\/v2\/media?parent=25408"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.dbu.de\/en\/wp-json\/wp\/v2\/categories?post=25408"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.dbu.de\/en\/wp-json\/wp\/v2\/tags?post=25408"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}