{"id":194587,"date":"2026-08-31T12:03:44","date_gmt":"2026-08-31T10:03:44","guid":{"rendered":"https:\/\/www.dbu.de\/?post_type=newsletter&#038;p=194587"},"modified":"2026-08-31T13:25:28","modified_gmt":"2026-08-31T11:25:28","slug":"dbu-jahresbericht-umweltprobleme-praktisch-loesen","status":"publish","type":"newsletter","link":"https:\/\/www.dbu.de\/en\/newsletter\/dbuaktuell-august-2026\/dbu-jahresbericht-umweltprobleme-praktisch-loesen\/","title":{"rendered":"DBU-Jahresbericht: Umweltprobleme praktisch l\u00f6sen"},"content":{"rendered":"\n<div class=\"wp-block-wordpress-dbu-dbu-container\">\n<figure class=\"wp-block-image alignleft size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"1920\" height=\"1280\" src=\"https:\/\/www.dbu.de\/app\/uploads\/dbu-media-2025-uwp-familienfoto-nah-1920x1280.jpg\" alt=\"\" class=\"wp-image-158872\" style=\"width:320px;height:auto\" srcset=\"https:\/\/www.dbu.de\/app\/uploads\/dbu-media-2025-uwp-familienfoto-nah-1920x1280.jpg 1920w, https:\/\/www.dbu.de\/app\/uploads\/dbu-media-2025-uwp-familienfoto-nah-800x533.jpg 800w, https:\/\/www.dbu.de\/app\/uploads\/dbu-media-2025-uwp-familienfoto-nah-400x267.jpg 400w, https:\/\/www.dbu.de\/app\/uploads\/dbu-media-2025-uwp-familienfoto-nah.jpg 2048w\" sizes=\"auto, (max-width: 1920px) 100vw, 1920px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Der DBU-Jahresbericht 2025 ist komplett: Anl\u00e4sslich der DBU-Jahrespressekonferenz ver\u00f6ffentlichte die Stiftung die abschlie\u00dfenden Kapitel auf der DBU-Webseite. <\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Zukunft beginnt dort, wo Umweltprobleme praktisch gel\u00f6st werden: in Unternehmen, die Materialien neu denken, in Forschungslaboren, die an klimafreundlichen Technologien arbeiten, oder in Projekten, die zeigen, wie sich Natur und Nutzung besser miteinander verbinden lassen.<\/p>\n\n\n\n<figure class=\"wp-block-image alignright size-full is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"375\" height=\"294\" src=\"https:\/\/www.dbu.de\/app\/uploads\/dbu-media-2025-vorwort-meeresnaturschutzfond-rgb-120x94px.jpg\" alt=\"\" class=\"wp-image-180285\" style=\"width:196px;height:auto\"\/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Wie aus solchen Ideen konkrete L\u00f6sungen f\u00fcr Umwelt- und Klimaschutz entstehen, zeigt die DBU in ihrem Jahresbericht 2025, der anl\u00e4sslich der DBU-Jahrespressekonferenz komplett ver\u00f6ffentlicht wurde<s>.<\/s> Thematisch im Mittelpunkt sind neben der <a href=\"https:\/\/www.dbu.de\/jahresbericht\/jahr-2025\/deutscher-umweltpreis\/\" target=\"_blank\" rel=\"noreferrer noopener\">Verleihung des Deutschen Umweltpreises<\/a> und dem <a href=\"https:\/\/www.dbu.de\/jahresbericht\/jahr-2025\/meeresnaturschutzfonds\/\" target=\"_blank\" rel=\"noreferrer noopener\">Meeresnaturschutzfonds<\/a> die <a href=\"https:\/\/www.dbu.de\/jahresbericht\/jahr-2025\/lebensmittelverluste\/\" target=\"_blank\" rel=\"noreferrer noopener\">Reduktion von Lebensmittelverlusten<\/a> entlang der gesamten Wertsch\u00f6pfungskette, eine <a href=\"https:\/\/www.dbu.de\/jahresbericht\/jahr-2025\/nachhaltige-landwirtschaft\/\" target=\"_blank\" rel=\"noreferrer noopener\">Landwirtschaft<\/a>, die Umweltbelastungen durch N\u00e4hrstoffe, Pestizide und Emissionen verringert und zugleich stabile Ertr\u00e4ge erm\u00f6glicht, sowie <a href=\"https:\/\/www.dbu.de\/jahresbericht\/jahr-2025\/klima-und-ressourcenschonendes-bauen\/\" target=\"_blank\" rel=\"noreferrer noopener\">Bauweisen<\/a>, die Energie- und Ressourcenverbrauch nachhaltig senken. Links zu einer Kurzfassung des Jahresberichtes, einer Projekt\u00fcbersicht und dem Finanzbericht finden sich im <a href=\"https:\/\/www.dbu.de\/jahresbericht\/jahr-2025\/vorwort\/\" target=\"_blank\" rel=\"noreferrer noopener\">Vorwort<\/a>.<\/p>\n\n\n\n<figure class=\"wp-block-image alignleft size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"1920\" height=\"1440\" src=\"https:\/\/www.dbu.de\/app\/uploads\/dbu-media-jahresbericht-3591801-wildkraeuter-zwischen-den-kulturreihen-cmagiera-dbu-1920x1440.jpg\" alt=\"\" class=\"wp-image-132574\" style=\"width:322px;height:auto\" srcset=\"https:\/\/www.dbu.de\/app\/uploads\/dbu-media-jahresbericht-3591801-wildkraeuter-zwischen-den-kulturreihen-cmagiera-dbu-1920x1440.jpg 1920w, https:\/\/www.dbu.de\/app\/uploads\/dbu-media-jahresbericht-3591801-wildkraeuter-zwischen-den-kulturreihen-cmagiera-dbu-800x600.jpg 800w, https:\/\/www.dbu.de\/app\/uploads\/dbu-media-jahresbericht-3591801-wildkraeuter-zwischen-den-kulturreihen-cmagiera-dbu-400x300.jpg 400w\" sizes=\"auto, (max-width: 1920px) 100vw, 1920px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Auch f\u00fcr das Jahr 2026 erscheint der DBU-Jahresbericht ausschlie\u00dflich digital, ganz im Sinne unserer eigenen Nachhaltigkeitsanspr\u00fcche. Die einzelnen Kapitel werden Schritt f\u00fcr Schritt online ver\u00f6ffentlicht. Die Stiftung unterst\u00fctzt gezielt Vorhaben, die \u00f6kologisches Handeln und wirtschaftlich tragf\u00e4hige Ans\u00e4tze zusammenbringen. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><em>Lesen Sie rein: <a href=\"https:\/\/www.dbu.de\/jahresbericht\/\" target=\"_blank\" rel=\"noreferrer noopener\">www.dbu.de\/jahresbericht\/<\/a><\/em><\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":34,"featured_media":152828,"parent":194576,"template":"","meta":{"footnotes":""},"newsletter-kategorie":[],"class_list":["post-194587","newsletter","type-newsletter","status-publish","has-post-thumbnail","hentry"],"meta_box":{"dbu_newsletter_gruppe_container":[{"dbu_newsletter_gruppe_container_select":"newsletter"}],"dbu_news_mail":"0","dbu_news_mail_status":"Eine Mail wurde nicht verschickt"},"_links":{"self":[{"href":"https:\/\/www.dbu.de\/en\/wp-json\/wp\/v2\/newsletter\/194587","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.dbu.de\/en\/wp-json\/wp\/v2\/newsletter"}],"about":[{"href":"https:\/\/www.dbu.de\/en\/wp-json\/wp\/v2\/types\/newsletter"}],"author":[{"embeddable":true,"href":"https:\/\/www.dbu.de\/en\/wp-json\/wp\/v2\/users\/34"}],"version-history":[{"count":11,"href":"https:\/\/www.dbu.de\/en\/wp-json\/wp\/v2\/newsletter\/194587\/revisions"}],"predecessor-version":[{"id":194792,"href":"https:\/\/www.dbu.de\/en\/wp-json\/wp\/v2\/newsletter\/194587\/revisions\/194792"}],"up":[{"embeddable":true,"href":"https:\/\/www.dbu.de\/en\/wp-json\/wp\/v2\/newsletter\/194576"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.dbu.de\/en\/wp-json\/wp\/v2\/media\/152828"}],"wp:attachment":[{"href":"https:\/\/www.dbu.de\/en\/wp-json\/wp\/v2\/media?parent=194587"}],"wp:term":[{"taxonomy":"newsletter-kategorie","embeddable":true,"href":"https:\/\/www.dbu.de\/en\/wp-json\/wp\/v2\/newsletter-kategorie?post=194587"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}