{"id":179782,"date":"2026-05-28T09:48:42","date_gmt":"2026-05-28T07:48:42","guid":{"rendered":"https:\/\/www.dbu.de\/?post_type=newsletter&#038;p=179782"},"modified":"2026-07-06T15:50:37","modified_gmt":"2026-07-06T13:50:37","slug":"fuer-klimaschutz-und-wirtschaftsstandort-positionspapier-zum-kunststoffrecycling","status":"publish","type":"newsletter","link":"https:\/\/www.dbu.de\/en\/newsletter\/dbuaktuell-mai-2026\/fuer-klimaschutz-und-wirtschaftsstandort-positionspapier-zum-kunststoffrecycling\/","title":{"rendered":"Positionspapier zum Kunststoffrecycling"},"content":{"rendered":"\n<div class=\"wp-block-wordpress-dbu-dbu-container\">\n<p class=\"wp-block-paragraph\"><strong>Das Positionspapier \u201eOptionen f\u00fcr einen funktionsf\u00e4higen Markt f\u00fcr Kunststoffrezyklate\u201c des Wuppertal Instituts im Auftrag der DBU skizziert sechs Ans\u00e4tze, die auf die Entwicklung eines selbsttragenden Markts f\u00fcr Kunststoffrezyklate abzielen.<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Die f\u00fcr Klima- und Ressourcenschutz sowie Unabh\u00e4ngigkeit von fossilen Rohstoffimporten immens wichtige Kunststoffrecycling-Branche ben\u00f6tigt bundesweit dringend neue Impulse f\u00fcr mehr Wettbewerbsf\u00e4higkeit. Zu diesem Schluss kommt eine Untersuchung des <a href=\"https:\/\/wupperinst.org\/index\/\" target=\"_blank\" rel=\"noreferrer noopener\">Wuppertal Instituts<\/a> im Auftrag der DBU. Besonders problematisch: Ab 1. Januar 2030 schreibt die bald in Kraft tretende EU-Verordnung f\u00fcr Verpackungen und Verpackungsabf\u00e4lle (<a href=\"https:\/\/environment.ec.europa.eu\/topics\/waste-and-recycling\/packaging-waste_en\" target=\"_blank\" rel=\"noreferrer noopener\"><em>Packaging and Packaging Waste Regulation, PPWR<\/em><\/a>) Mindestquoten f\u00fcr Rezyklate vor. Wegen fehlender Investitionssicherheit geben jedoch immer mehr Kunststoffrecycling-Betriebe auf, Know -how geht verloren und es droht eine \u201eRezyklatl\u00fccke\u201c.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ein <a href=\"https:\/\/www.dbu.de\/app\/uploads\/dbu-media-2026-positionspapier-rezyklatmarkt-final-2.pdf\" target=\"_blank\" rel=\"noreferrer noopener\">Positionspapier<\/a>, das Anfang Mai auf der <a href=\"https:\/\/www.dbu.de\/termine\/ifat-2026-muenchen-weltleitmesse-fuer-umwelttechnologien\/\" target=\"_blank\" rel=\"noreferrer noopener\">Umwelttechnologie-Messe IFAT in M\u00fcnchen<\/a> pr\u00e4sentiert wurde, schl\u00e4gt sechs L\u00f6sungen zur Rettung der Branche vor:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Die \u00f6ffentliche Beschaffung muss st\u00e4rker als Hebel genutzt werden, um Recyclingtechnologien f\u00fcr Kunststoffe zu skalieren.<\/li>\n\n\n\n<li>Das Konzept der Mindestrezyklatquoten sollte erg\u00e4nzt werden um einen effizienten Allokationsmechanismus analog zum Emissionshandel.<\/li>\n\n\n\n<li>Es braucht eine deutliche Beschleunigung von Planungs- und Genehmigungsverfahren.<\/li>\n\n\n\n<li>Ebenso n\u00f6tig ist es, dieMaterialvielfalt eingesetzter Kunststoffe zu verringern, um \u00f6konomisch rentable Recyclingverfahren zu entwickeln.<\/li>\n\n\n\n<li>Globale Standards f\u00fcr die erweiterte Herstellerveranwortung: Externalisierte Umweltkosten bei der Kunststoffherstellung sollten durch eine Abgabe kompensiert werden.<\/li>\n\n\n\n<li>Die Transformation zur zirkul\u00e4ren Nutzung von Kunststoffen braucht die gezielte F\u00f6rderung neuer Gesch\u00e4ftsmodelle.<\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">Das geplante Aktionsprogramm der Nationalen Kreislaufwirtschaftsstrategie (NKWS) bietet daf\u00fcr gute Umsetzungsoptionen, die aus Sicht der DBU gerade im Bereich der Kunststoffe rasch angewendet werden sollten.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><em>Mehr dazu in unserer Pressemitteilung unter: <br><a href=\"http:\/\/www.dbu.de\/news\/dbu-mehr-kunststoff-recycling-sichert-klimaschutz-und-wirtschaftsstandort\/\" target=\"_blank\" rel=\"noreferrer noopener\">www.dbu.de\/news\/dbu-mehr-kunststoff-recycling-sichert-klimaschutz-und-wirtschaftsstandort\/<\/a> <\/em><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><em>Das Positionspapier gibt es hier zum Download: <br><a href=\"http:\/\/www.dbu.de\/app\/uploads\/dbu-media-2026-positionspapier-rezyklatmarkt-final-2.pdf\" target=\"_blank\" rel=\"noreferrer noopener\">www.dbu.de\/app\/uploads\/dbu-media-2026-positionspapier-rezyklatmarkt-final-2.pdf<\/a><\/em><\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":34,"featured_media":179738,"parent":179748,"template":"","meta":{"footnotes":""},"newsletter-kategorie":[],"class_list":["post-179782","newsletter","type-newsletter","status-publish","has-post-thumbnail","hentry"],"meta_box":{"dbu_newsletter_gruppe_container":[{"dbu_newsletter_gruppe_container_select":"newsletter"}],"dbu_news_mail":"0","dbu_news_mail_status":"Eine Mail wurde nicht verschickt"},"_links":{"self":[{"href":"https:\/\/www.dbu.de\/en\/wp-json\/wp\/v2\/newsletter\/179782","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.dbu.de\/en\/wp-json\/wp\/v2\/newsletter"}],"about":[{"href":"https:\/\/www.dbu.de\/en\/wp-json\/wp\/v2\/types\/newsletter"}],"author":[{"embeddable":true,"href":"https:\/\/www.dbu.de\/en\/wp-json\/wp\/v2\/users\/34"}],"version-history":[{"count":6,"href":"https:\/\/www.dbu.de\/en\/wp-json\/wp\/v2\/newsletter\/179782\/revisions"}],"predecessor-version":[{"id":179873,"href":"https:\/\/www.dbu.de\/en\/wp-json\/wp\/v2\/newsletter\/179782\/revisions\/179873"}],"up":[{"embeddable":true,"href":"https:\/\/www.dbu.de\/en\/wp-json\/wp\/v2\/newsletter\/179748"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.dbu.de\/en\/wp-json\/wp\/v2\/media\/179738"}],"wp:attachment":[{"href":"https:\/\/www.dbu.de\/en\/wp-json\/wp\/v2\/media?parent=179782"}],"wp:term":[{"taxonomy":"newsletter-kategorie","embeddable":true,"href":"https:\/\/www.dbu.de\/en\/wp-json\/wp\/v2\/newsletter-kategorie?post=179782"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}