{"id":179776,"date":"2026-05-28T09:48:41","date_gmt":"2026-05-28T07:48:41","guid":{"rendered":"https:\/\/www.dbu.de\/?post_type=newsletter&#038;p=179776"},"modified":"2026-07-06T15:50:37","modified_gmt":"2026-07-06T13:50:37","slug":"mehrweg-statt-wegwerfplastik-wiederverwendbare-trays-fuer-topfpflanzen","status":"publish","type":"newsletter","link":"https:\/\/www.dbu.de\/en\/newsletter\/dbuaktuell-mai-2026\/mehrweg-statt-wegwerfplastik-wiederverwendbare-trays-fuer-topfpflanzen\/","title":{"rendered":"Mehrweg statt Wegwerfplastik: Wiederverwendbare Trays f\u00fcr Topfpflanzen"},"content":{"rendered":"\n<div class=\"wp-block-wordpress-dbu-dbu-container\">\n<p class=\"wp-block-paragraph\"><strong>Mehrweg-Trays f\u00fcr Topfpflanzen sparen Ressourcen und CO<sub>2<\/sub>. Die Markteinf\u00fchrung l\u00e4uft: Bis zum Jahr 2030 sollen europaweit 150 Millionen Trays im Umlauf sein.<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Fr\u00fchlingszeit ist Pflanzzeit: Damit Topfpflanzen in die Baum\u00e4rkte oder Gartencenter gelangen, werden sie in Pflanzenpaletten aus Kunststoff, den sogenannten Trays, transportiert. J\u00e4hrlich werden europaweit 500 bis 700 Millionen Trays eingesetzt \u2013 und dann entsorgt, denn \u00fcber 95 Prozent sind Einwegprodukte.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Um dies zu \u00e4ndern, gr\u00fcndete sich im Jahr 2022 die Euro Plant Tray eG als Initiative f\u00fchrender Unternehmen der Gartenbaubranche, die gemeinsam den europ\u00e4ischen Branchenstandard f\u00fcr Mehrweg-Trays entwickelten. Mit Unterst\u00fctzung der DBU wurden dann weitere Schritte zur erfolgreichen Markteinf\u00fchrung eines Mehrwegsystems angegangen: In Workshops mit Produzierenden, Gro\u00dfh\u00e4ndlern und Retailern wurden Kriterien f\u00fcr Tray-Formate erarbeitet und drei neue Mehrweg-Tray-Formen entwickelt. Die Ergebnisse dieser Workshops wurden von den Tray-Herstellern aufgegriffen und die neu konzipierten Trays per 3D-Druck erstellt und mit Beteiligten der gesamten Lieferkette getestet. Zudem wurde ein Logistikkonzept erarbeitet.<\/p>\n\n\n\n<figure class=\"wp-block-image alignleft size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"1920\" height=\"1440\" src=\"https:\/\/www.dbu.de\/app\/uploads\/dbu-media-mai-2026-38737-tray-produktion-1920x1440.jpg\" alt=\"\" class=\"wp-image-179779\" style=\"width:456px;height:auto\" srcset=\"https:\/\/www.dbu.de\/app\/uploads\/dbu-media-mai-2026-38737-tray-produktion-1920x1440.jpg 1920w, https:\/\/www.dbu.de\/app\/uploads\/dbu-media-mai-2026-38737-tray-produktion-800x600.jpg 800w, https:\/\/www.dbu.de\/app\/uploads\/dbu-media-mai-2026-38737-tray-produktion-400x300.jpg 400w\" sizes=\"auto, (max-width: 1920px) 100vw, 1920px\" \/><figcaption class=\"wp-element-caption\">Produktion der Mehrweg-Trays<\/figcaption><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Eine projektbegleitende Studie durch das Unternehmen Greenhouse Sustainability ergab: Schon nach vier Uml\u00e4ufen \u2013 Mehrweg-Pflanzentrays sind f\u00fcr eine Lebensdauer von 50 bis 100 Uml\u00e4ufen angelegt \u2013 weisen die Mehrweg-Trays einen besseren CO<sub>2<\/sub>-Fu\u00dfabdruck auf als Einweg-Trays. Bei 100 Uml\u00e4ufen k\u00f6nnen 96 Prozent des CO<sub>2 <\/sub>eingespart werden.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Mehrweg-Trays bereits im Einsatz<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Teile der Produktion und der Markteinf\u00fchrung laufen bereits. Mehrere bekannte Baumarktketten in Deutschland, \u00d6sterreich und weiteren europ\u00e4ischen L\u00e4ndern, darunter Hornbach, Bauhaus, Globus, OBI sowie Bellaflora nutzen die Mehrweg-Trays. Stand Ende 2025 waren bereits 1,7 Millionen Trays im Umlauf. Bis sp\u00e4testens 2030 sollen es europaweit rund 150 Millionen Mehrweg-Trays sein, die dann die 700 Millionen Einweg-Trays ersetzen \u2013 umso mehr, als dann die europ\u00e4ische Verpackungsrichtline (PPWR) greift. Dann d\u00fcrfen die bisher genutzten Einweg-Trays in den allermeisten Lieferketten nicht mehr genutzt werden. Die Europe Plant Tray eG bietet nun eine umweltfreundliche, kreislauff\u00e4hige L\u00f6sung f\u00fcr die gesamte Branche.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><em>Abschlussbericht unter: <\/em><a href=\"https:\/\/opac.dbu.de\/ab\/DBU-Abschlussbericht-AZ-38737_01-Hauptbericht.pdf\" target=\"_blank\" rel=\"noreferrer noopener\"><em>DBU-Abschlussbericht-AZ-38737_01-Hauptbericht.pdf<\/em><\/a><br>AZ<a href=\"https:\/\/www.dbu.de\/projektdatenbank\/38737-01\/\" data-type=\"link\" data-id=\"https:\/\/www.dbu.de\/projektdatenbank\/38737-01\/\" target=\"_blank\" rel=\"noreferrer noopener\"> 38737<\/a><\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":34,"featured_media":179740,"parent":179748,"template":"","meta":{"footnotes":""},"newsletter-kategorie":[],"class_list":["post-179776","newsletter","type-newsletter","status-publish","has-post-thumbnail","hentry"],"meta_box":{"dbu_newsletter_gruppe_container":[{"dbu_newsletter_gruppe_container_select":"newsletter"}],"dbu_news_mail":"0","dbu_news_mail_status":"Eine Mail wurde nicht verschickt"},"_links":{"self":[{"href":"https:\/\/www.dbu.de\/en\/wp-json\/wp\/v2\/newsletter\/179776","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.dbu.de\/en\/wp-json\/wp\/v2\/newsletter"}],"about":[{"href":"https:\/\/www.dbu.de\/en\/wp-json\/wp\/v2\/types\/newsletter"}],"author":[{"embeddable":true,"href":"https:\/\/www.dbu.de\/en\/wp-json\/wp\/v2\/users\/34"}],"version-history":[{"count":7,"href":"https:\/\/www.dbu.de\/en\/wp-json\/wp\/v2\/newsletter\/179776\/revisions"}],"predecessor-version":[{"id":179846,"href":"https:\/\/www.dbu.de\/en\/wp-json\/wp\/v2\/newsletter\/179776\/revisions\/179846"}],"up":[{"embeddable":true,"href":"https:\/\/www.dbu.de\/en\/wp-json\/wp\/v2\/newsletter\/179748"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.dbu.de\/en\/wp-json\/wp\/v2\/media\/179740"}],"wp:attachment":[{"href":"https:\/\/www.dbu.de\/en\/wp-json\/wp\/v2\/media?parent=179776"}],"wp:term":[{"taxonomy":"newsletter-kategorie","embeddable":true,"href":"https:\/\/www.dbu.de\/en\/wp-json\/wp\/v2\/newsletter-kategorie?post=179776"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}