{"id":178431,"date":"2026-04-30T11:12:48","date_gmt":"2026-04-30T09:12:48","guid":{"rendered":"https:\/\/www.dbu.de\/?post_type=newsletter&#038;p=178431"},"modified":"2026-04-30T13:11:11","modified_gmt":"2026-04-30T11:11:11","slug":"wir-unterstuetzen-gute-ideen-zur-flexibilisierung-industrieller-lasten-interview-zur-dbu-foerderinitiative-speicher-und-netze","status":"publish","type":"newsletter","link":"https:\/\/www.dbu.de\/en\/newsletter\/dbuaktuell-april-2026\/wir-unterstuetzen-gute-ideen-zur-flexibilisierung-industrieller-lasten-interview-zur-dbu-foerderinitiative-speicher-und-netze\/","title":{"rendered":"\u201eWir unterst\u00fctzen gute Ideen zur Flexibilisierung industrieller Lasten\u201c \u2013 Interview zur DBU-F\u00f6rderinitiative Speicher und Netze"},"content":{"rendered":"\n<div class=\"wp-block-wordpress-dbu-dbu-container\">\n<p class=\"wp-block-paragraph\"><strong>Seit September 2024 schreibt die DBU die F\u00f6rderinitiative \u201e<a href=\"https:\/\/www.dbu.de\/themen\/foerderinitiativen\/speicher-und-netze\/\" data-type=\"link\" data-id=\"https:\/\/www.dbu.de\/themen\/foerderinitiativen\/speicher-und-netze\/\" target=\"_blank\" rel=\"noreferrer noopener\">Speicher und Netze \u2013 Dezentrale saisonale Stromspeicher und netzdienliche Innovationen<\/a>\u201c aus und m\u00f6chte damit einen Beitrag zum Gelingen der Energiewende leisten. Inzwischen sind 14 Projekte und 10 Ideen aus einem Ideenwettbewerb gef\u00f6rdert worden. Dr. Katrin Anneser ist eine der Ansprechpartnerinnen f\u00fcr die F\u00f6rderinitiative. Im Interview erz\u00e4hlt sie, warum es gerade jetzt bei der Energiewende spannend wird, wie zuk\u00fcnftige Stromnetze aussehen und warum man sich den 16. Juni im Kalender eintragen sollte.<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong><em>DBUaktuell:<\/em><\/strong> Warum ist das Thema \u201eSpeicher und Netze\u201c nach wie vor ein Schwerpunktthema, das durch eine explizite F\u00f6rderinitiative vorangebracht wird?<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong><em>Dr. Katrin Anneser:<\/em><\/strong> Gerade die aktuelle Weltlage zeigt, wie relevant die Energiewende ist. Zum einen geht es nach wie vor um die Eind\u00e4mmung der CO<sub>2<\/sub>-Emissionen. Aber es geht immer deutlicher auch um die geopolitische Unabh\u00e4ngigkeit Deutschlands und Europas sowie die Strompreise. Au\u00dferdem befinden wir uns geraden an einem spannenden Punkt der Energiewende: Wir m\u00fcssen unser Stromsystem fit machen f\u00fcr mehr und mehr fluktuierende erneuerbare Energie \u2013 das hei\u00dft, f\u00fcr das wechselnde Angebot insbesondere aus Photovoltaik- und Windkraftanlagen. Darauf m\u00fcssen wir auf der Seite des Energieverbrauchs flexibel reagieren, um das Abregeln von einzelnen Anlagen und \u201eBlackouts\u201c zu vermeiden. L\u00f6sungsans\u00e4tze hierf\u00fcr suchen wir mit der Ausschreibung \u201e<a href=\"https:\/\/www.dbu.de\/app\/uploads\/dbu_media-Foerderinitiative-Netze-Speicher-Ausschreibungstext-_Netzdienliche-Innovationen_.pdf\" data-type=\"link\" data-id=\"https:\/\/www.dbu.de\/app\/uploads\/dbu_media-Foerderinitiative-Netze-Speicher-Ausschreibungstext-_Netzdienliche-Innovationen_.pdf\" target=\"_blank\" rel=\"noreferrer noopener\">Netzdienliche Innovationen<\/a>\u201c. Ein weiterer Ansatzpunkt ist es, Energie aus dem Sommer f\u00fcr den Winter zu speichern. Darum unterst\u00fctzen wir die <a href=\"https:\/\/www.dbu.de\/app\/uploads\/dbu_media-Foerderinitiative-Netze-Speicher-Ausschreibungstext-_Dezentrale-Saisonale-Stromspeicher_.pdf\" target=\"_blank\" rel=\"noreferrer noopener\">Entwicklung innovativer Saisonalspeicherkonzepte <\/a>mit dem zweiten Teil der F\u00f6rderinitiative.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong><em>DBUaktuell:<\/em><\/strong> Welche Erkenntnisse gibt es aus der bisherigen F\u00f6rderung?<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Anneser:<\/strong> Zum einen sehen wir die netzdienliche, aber dennoch wirtschaftliche Systemeinbindung von Gro\u00dfbatterien. Aber wir verfolgen auch noch einen weiteren Ansatz: Wir unterst\u00fctzen insbesondere den Mittelstand dabei, gute Ideen zur Flexibilisierung industrieller Lasten zu entwickeln \u2013 also daf\u00fcr, den Strombedarf von Produktionsanlagen flexibel zu regeln und beispielsweise Energie\u00fcbersch\u00fcsse zu speichern. Hier f\u00f6rdern wir bereits mehrere Projekte und Gesch\u00e4ftsmodelle. Das Flexibilisierungspotential der Industrie ist riesig!<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Bei den saisonalen Speichern favorisieren andere F\u00f6rderprogramme vorrangig Wasserstoff. F\u00fcr Alternativen wie Ammoniak oder das Redoxpotenzial von Metallen oder klassische Ans\u00e4tze wie Zink-Mangan zeigen sich wenig F\u00f6rderm\u00f6glichkeiten. Hier setzt unsere F\u00f6rderinitiative an, indem sie Ideen evaluiert und sich so als Ausgangspunkt f\u00fcr konkrete Weiterentwicklungen in und au\u00dferhalb der DBU-F\u00f6rderung zeigt.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong><em>DBUaktuell:<\/em><\/strong> Wie sehen die genannten Ideen und Projekte konkret aus?<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong><em>Anneser: <\/em><\/strong>Ein <a href=\"https:\/\/www.dbu.de\/newsletter\/dbuaktuell-nr-september-2025\/vom-stadthafen-zum-klimahafen-gelsenkirchen\/\" target=\"_blank\" rel=\"noreferrer noopener\">Projekt zusammen mit der ZINQ GmbH &amp; Co. KG<\/a> aus Gelsenkirchen zeigt, was sich hinter dem genannten Flexibilisierungspotenzial verbirgt: Es wurde ein Konzept untersucht, bei dem flexibel erneuerbarer \u00dcberschussstrom oder Gas \u2013 in Zukunft: gr\u00fcner Wasserstoff \u2013 zum Erzeugen von Prozessw\u00e4rme genutzt wird. W\u00fcrde dieses Konzept auf die gesamte industrielle Prozessw\u00e4rmeerzeugung \u00fcbertragen, sind bis zu 115\u00a0Terawattstunden \u00dcberschussstrom nutzbar, was einer CO\u2082-Minderung von bis zu 30 Mio. Tonnen pro Jahr ent\u00adsprechen w\u00fcrde. Zudem sind diese L\u00f6sungen vier- bis f\u00fcnfmal g\u00fcnstiger als Batteriespeicher. Ein <a href=\"https:\/\/www.dbu.de\/newsletter\/dbuaktuell-april-2026\/zukunftsfaehiges-energiemanagement-fuer-ortsnetze\/\" data-type=\"link\" data-id=\"https:\/\/www.dbu.de\/newsletter\/dbuaktuell-april-2026\/zukunftsfaehiges-energiemanagement-fuer-ortsnetze\/\" target=\"_blank\" rel=\"noreferrer noopener\">Zukunftsszenario f\u00fcr das Jahr 2035 <\/a>zu entwickeln, ist eine Idee der Promovendin Catherine Adelmann an der Technischen Hochschule Ulm. Sie ber\u00fccksichtigt dabei die zunehmende Photovoltaik-Erzeugung sowie den steigenden Strombedarf durch Elektromobilit\u00e4t und W\u00e4rmepumpen und bindet bestehende Anlagen mit ein. Und das <a href=\"https:\/\/www.dbu.de\/newsletter\/dbuaktuell-april-2026\/neue-speichertechnologie-nutzt-sand-wasser-und-physik\/\" data-type=\"link\" data-id=\"https:\/\/www.dbu.de\/newsletter\/dbuaktuell-april-2026\/neue-speichertechnologie-nutzt-sand-wasser-und-physik\/\" target=\"_blank\" rel=\"noreferrer noopener\">Start-up idyl <\/a>aus Hamburg arbeitet an einem Speicher, der nicht nur elektrische Energie, sondern auch W\u00e4rme bereitstellen kann und als Speichermedien Wasser und Sand nutzt. Weitere Ideen und L\u00f6sungen lassen sich auf unserer Webseite <a href=\"http:\/\/www.dbu.de\/themen\/foerderinitiativen\/speicher-und-netze\/\" target=\"_blank\" rel=\"noreferrer noopener\">www.dbu.de\/themen\/foerderinitiativen\/speicher-und-netze\/<\/a> entdecken.<\/p>\n\n\n\n<figure class=\"wp-block-image alignleft size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"1920\" height=\"1280\" src=\"https:\/\/www.dbu.de\/app\/uploads\/dbu-media-querformat-dbu-anneser-katrin-1920x1280.jpg\" alt=\"Dr. Kathrin Anneser\" class=\"wp-image-129199\" style=\"width:323px;height:auto\" srcset=\"https:\/\/www.dbu.de\/app\/uploads\/dbu-media-querformat-dbu-anneser-katrin-1920x1280.jpg 1920w, https:\/\/www.dbu.de\/app\/uploads\/dbu-media-querformat-dbu-anneser-katrin-800x533.jpg 800w, https:\/\/www.dbu.de\/app\/uploads\/dbu-media-querformat-dbu-anneser-katrin-400x267.jpg 400w\" sizes=\"auto, (max-width: 1920px) 100vw, 1920px\" \/><figcaption class=\"wp-element-caption\">Dr. Kathrin Anneser ist eine Ansprechpartnerin f\u00fcr die DBU-F\u00f6rderinitiative &#8220;Speicher und Netze&#8221;.<\/figcaption><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\"><strong><em>DBUaktuell<\/em><\/strong><em>:<\/em> Wie geht es mit diesen Entwicklungen in Zukunft weiter?<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong><em>Anneser: <\/em><\/strong>Derzeit l\u00e4sst sich mit dem Zur-Verf\u00fcgung-Stellen von Flexibilit\u00e4ten, also dem Handeln mit Strom, Gewinn erzielen, weil die Preise an der Stromb\u00f6rse stark schwanken. Zuk\u00fcnftig werden zwei Dinge passieren:<\/p>\n\n\n\n<ol class=\"wp-block-list\">\n<li>Es wird lokale finanzielle Anreize geben m\u00fcssen, um Flexibilit\u00e4ten netzdienlich zu betreiben, beispielsweise dynamische Netzentgelte. Nach aktuellem Stand kann ein s\u00fcddeutscher Gro\u00dfbatteriespeicher Geld verdienen, wenn die Windr\u00e4der in der Nordsee viel Strom liefern. Das belastet das Stromnetz. Besser w\u00e4re es, wenn dieser Speicher auf die nahe gelegenen Solaranlagen reagieren w\u00fcrde. Das kann durch lokale Preissignale erreicht werden.<\/li>\n\n\n\n<li>Je mehr Flexibilit\u00e4ten wie zum Beispiel zeitlich steuerbare industrielle Lasten oder Stromspeicher am Netz sind, desto kleiner wird der Preishub f\u00fcr netzausgleichende Ma\u00dfnahmen. Dieser L\u00f6sungsweg zur Netzstabilit\u00e4t kannibalisiert sich durch das abnehmende Gewinnversprechen daher mit der Zeit selbst. Dadurch kommen wir aber zu genau dem Stromsystem, das wir in Zukunft ben\u00f6tigen: Die Lasten folgen der Erzeugung. Wie sich dann die Gesch\u00e4ftsmodelle weiterentwickeln, bleibt spannend.<\/li>\n<\/ol>\n\n\n\n<p class=\"wp-block-paragraph\"><strong><em>DBUaktuell<\/em>:<\/strong> Und wie geht es mit der F\u00f6rderinitiative weiter?<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong><em>Anneser:<\/em><\/strong> F\u00fcr alle, die sich vertieft mit dem Thema besch\u00e4ftigen wollen, Anregungen suchen oder Vorschl\u00e4ge diskutieren m\u00f6chten, bieten wir am 16. Juni 2026 die Gelegenheit, sich zu vernetzen. Bei der <a href=\"https:\/\/www.dbu.de\/termine\/dbu-fachtagung-speicher-und-netze\/\" target=\"_blank\" rel=\"noreferrer noopener\">Fachtagung Speicher und Netze<\/a> in Osnabr\u00fcck wird \u00fcber die Projektergebnisse der F\u00f6rderinitiative und weiterf\u00fchrende Ideen berichtet und Raum f\u00fcr den vertieften Austausch geschaffen. Au\u00dferdem freuen wir uns nach wie vor \u00fcber innovative Projektideen \u2013 solange es die gibt, l\u00e4uft die F\u00f6rderinitiative weiter.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><em>Mehr zur F\u00f6rderinitiative Speicher und Netze unter: <\/em><br><a href=\"http:\/\/www.dbu.de\/themen\/foerderinitiativen\/speicher-und-netze\/\" target=\"_blank\" rel=\"noreferrer noopener\"><em>www.dbu.de\/themen\/foerderinitiativen\/speicher-und-netze\/<\/em><\/a><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><em>Programm und Anmeldem\u00f6glichkeit zur Fachtagung finden sich hier: <\/em><br><a href=\"http:\/\/www.dbu.de\/termine\/dbu-fachtagung-speicher-und-netze\/\" target=\"_blank\" rel=\"noreferrer noopener\"><em>www.dbu.de\/termine\/dbu-fachtagung-speicher-und-netze\/<\/em><\/a><\/p>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n\n<p class=\"wp-block-paragraph\"><a id=\"_msocom_1\"><\/a><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":34,"featured_media":102745,"parent":178425,"template":"","meta":{"footnotes":""},"newsletter-kategorie":[],"class_list":["post-178431","newsletter","type-newsletter","status-publish","has-post-thumbnail","hentry"],"meta_box":{"dbu_newsletter_gruppe_container":[{"dbu_newsletter_gruppe_container_select":"newsletter"}],"dbu_news_mail":"0","dbu_news_mail_status":"Eine Mail wurde nicht verschickt"},"_links":{"self":[{"href":"https:\/\/www.dbu.de\/en\/wp-json\/wp\/v2\/newsletter\/178431","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.dbu.de\/en\/wp-json\/wp\/v2\/newsletter"}],"about":[{"href":"https:\/\/www.dbu.de\/en\/wp-json\/wp\/v2\/types\/newsletter"}],"author":[{"embeddable":true,"href":"https:\/\/www.dbu.de\/en\/wp-json\/wp\/v2\/users\/34"}],"version-history":[{"count":17,"href":"https:\/\/www.dbu.de\/en\/wp-json\/wp\/v2\/newsletter\/178431\/revisions"}],"predecessor-version":[{"id":178725,"href":"https:\/\/www.dbu.de\/en\/wp-json\/wp\/v2\/newsletter\/178431\/revisions\/178725"}],"up":[{"embeddable":true,"href":"https:\/\/www.dbu.de\/en\/wp-json\/wp\/v2\/newsletter\/178425"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.dbu.de\/en\/wp-json\/wp\/v2\/media\/102745"}],"wp:attachment":[{"href":"https:\/\/www.dbu.de\/en\/wp-json\/wp\/v2\/media?parent=178431"}],"wp:term":[{"taxonomy":"newsletter-kategorie","embeddable":true,"href":"https:\/\/www.dbu.de\/en\/wp-json\/wp\/v2\/newsletter-kategorie?post=178431"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}