{"id":193482,"date":"2026-07-14T08:54:00","date_gmt":"2026-07-14T06:54:00","guid":{"rendered":"https:\/\/www.dbu.de\/app\/uploads\/dbu-media-reiterswiesen-bienen-ragwurz-tobias-leikauf-dbu-naturerbe.jpg"},"modified":"2026-07-14T08:59:34","modified_gmt":"2026-07-14T06:59:34","slug":"bienen-ragwurz_dbu-naturerbeflaeche-reiterswiesen-2","status":"inherit","type":"attachment","link":"https:\/\/www.dbu.de\/en\/bienen-ragwurz_dbu-naturerbeflaeche-reiterswiesen-2\/","title":{"rendered":"Bienen-Ragwurz_DBU-Naturerbefl\u00e4che Reiterswiesen"},"author":11,"featured_media":0,"comment_status":"closed","ping_status":"closed","template":"","meta":[],"class_list":["post-193482","attachment","type-attachment","status-inherit","hentry"],"meta_box":{"dbu_image_usage":"","dbu_image_download":"","dbu_image_copyright":"","dbu_image_copyright_hidden":""},"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/www.dbu.de\/app\/uploads\/dbu-media-reiterswiesen-bienen-ragwurz-tobias-leikauf-dbu-naturerbe-scaled.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"579\" height=\"800\" src=\"https:\/\/www.dbu.de\/app\/uploads\/dbu-media-reiterswiesen-bienen-ragwurz-tobias-leikauf-dbu-naturerbe-579x800.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/www.dbu.de\/app\/uploads\/dbu-media-reiterswiesen-bienen-ragwurz-tobias-leikauf-dbu-naturerbe-579x800.jpg 579w, https:\/\/www.dbu.de\/app\/uploads\/dbu-media-reiterswiesen-bienen-ragwurz-tobias-leikauf-dbu-naturerbe-1390x1920.jpg 1390w, https:\/\/www.dbu.de\/app\/uploads\/dbu-media-reiterswiesen-bienen-ragwurz-tobias-leikauf-dbu-naturerbe-290x400.jpg 290w, https:\/\/www.dbu.de\/app\/uploads\/dbu-media-reiterswiesen-bienen-ragwurz-tobias-leikauf-dbu-naturerbe-scaled.jpg 1853w\" sizes=\"auto, (max-width: 579px) 100vw, 579px\" \/><\/a><\/p>\n"},"caption":{"rendered":"<p>Rechtliches:<br \/>\nDie Verwendung dieses Bildes ist ausschlie\u00dflich im Rahmen redaktioneller Berichterstattung mit inhaltlichen Bez\u00fcgen zur Deutschen Bundesstiftung Umwelt (DBU) erlaubt. Das Bild kann zu diesem Zweck vervielf\u00e4ltigt und kostenlos ver\u00f6ffentlicht werden. Alle angebotenen Bilder durch die Bilddatenbank piclease d\u00fcrfen nicht f\u00fcr die Sozialen Medien verwendet werden. Die Bearbeitung des Bildes ist nicht erlaubt. Verkleinerungen oder Vergr\u00f6\u00dferungen, die der technischen Aufbereitung zum Zweck der optimalen Vervielf\u00e4ltigung dienen, sowie eine den zentralen Sinn des Bildes nicht entstellende Ausschnittwahl sind zul\u00e4ssig. <\/p>\n<p>Als Autoren- und Quellenangabe ist bei jeder Ver\u00f6ffentlichung des Bildes zu nennen:<br \/>\nFoto: DBU &#8211; Deutsche Bundesstiftung Umwelt<br \/>\nR\u00fcckfragen unter Telefon 0541\/9633-521<\/p>\n"},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":1853,"height":2560,"file":"dbu-media-reiterswiesen-bienen-ragwurz-tobias-leikauf-dbu-naturerbe-scaled.jpg","filesize":599020,"sizes":{"medium":{"file":"dbu-media-reiterswiesen-bienen-ragwurz-tobias-leikauf-dbu-naturerbe-579x800.jpg","width":579,"height":800,"filesize":91815,"mime_type":"image\/jpeg","source_url":"https:\/\/www.dbu.de\/app\/uploads\/dbu-media-reiterswiesen-bienen-ragwurz-tobias-leikauf-dbu-naturerbe-579x800.jpg"},"large":{"file":"dbu-media-reiterswiesen-bienen-ragwurz-tobias-leikauf-dbu-naturerbe-1390x1920.jpg","width":1390,"height":1920,"filesize":337236,"mime_type":"image\/jpeg","source_url":"https:\/\/www.dbu.de\/app\/uploads\/dbu-media-reiterswiesen-bienen-ragwurz-tobias-leikauf-dbu-naturerbe-1390x1920.jpg"},"thumbnail":{"file":"dbu-media-reiterswiesen-bienen-ragwurz-tobias-leikauf-dbu-naturerbe-290x400.jpg","width":290,"height":400,"filesize":43943,"mime_type":"image\/jpeg","source_url":"https:\/\/www.dbu.de\/app\/uploads\/dbu-media-reiterswiesen-bienen-ragwurz-tobias-leikauf-dbu-naturerbe-290x400.jpg"},"full":{"file":"dbu-media-reiterswiesen-bienen-ragwurz-tobias-leikauf-dbu-naturerbe-scaled.jpg","width":1853,"height":2560,"mime_type":"image\/jpeg","source_url":"https:\/\/www.dbu.de\/app\/uploads\/dbu-media-reiterswiesen-bienen-ragwurz-tobias-leikauf-dbu-naturerbe-scaled.jpg"}},"image_meta":{"aperture":"1.8","credit":"Tobias Leikauf\/DBU Naturerbe","camera":"Galaxy S24","caption":"Rechtliches:\rDie Verwendung dieses Bildes ist ausschlie\u00dflich im Rahmen redaktioneller Berichterstattung mit inhaltlichen Bez\u00fcgen zur Deutschen Bundesstiftung Umwelt (DBU) erlaubt. Das Bild kann zu diesem Zweck vervielf\u00e4ltigt und kostenlos ver\u00f6ffentlicht werden. Alle angebotenen Bilder durch die Bilddatenbank piclease d\u00fcrfen nicht f\u00fcr die Sozialen Medien verwendet werden. Die Bearbeitung des Bildes ist nicht erlaubt. Verkleinerungen oder Vergr\u00f6\u00dferungen, die der technischen Aufbereitung zum Zweck der optimalen Vervielf\u00e4ltigung dienen, sowie eine den zentralen Sinn des Bildes nicht entstellende Ausschnittwahl sind zul\u00e4ssig. \r\r\rAls Autoren- und Quellenangabe ist bei jeder Ver\u00f6ffentlichung des Bildes zu nennen: \rFoto: DBU - Deutsche Bundesstiftung Umwelt\rR\u00fcckfragen unter Telefon 0541\/9633-521","created_timestamp":"1781195615","copyright":"","focal_length":"5.4","iso":"25","shutter_speed":"0.003649635","title":"Bienen-Ragwurz_DBU-Naturerbefl\u00e4che Reiterswiesen","orientation":"1","keywords":["Deutsche Bundesstiftung Umwelt","DBU","DBU-Naturerbe","DBU-Naturerbefl\u00e4che","Nationales Naturerbe","Naturschutz","\u00d6kologie","\u00f6kologisch","Umweltschutz","biologische Vielfalt","Biodiversit\u00e4t","Lebensraum","\u00d6kosystem","\u00d6kosystemleistungen","Landschaft","Wildtiere","Artenvielfalt","Naturschutzmanagement","Offenland","Halboffenland","Weide","Wiese","Weideland","Weidelandschaft","Beweidung","Ganzjahresbeweidung","Mischbeweidung","Hirtentum","Haustierrasse","robust","Schafe"],"alt":""},"original_image":"dbu-media-reiterswiesen-bienen-ragwurz-tobias-leikauf-dbu-naturerbe.jpg"},"post":null,"source_url":"https:\/\/www.dbu.de\/app\/uploads\/dbu-media-reiterswiesen-bienen-ragwurz-tobias-leikauf-dbu-naturerbe-scaled.jpg","filename":"dbu-media-reiterswiesen-bienen-ragwurz-tobias-leikauf-dbu-naturerbe.jpg","filesize":599020,"_links":{"self":[{"href":"https:\/\/www.dbu.de\/en\/wp-json\/wp\/v2\/media\/193482","targetHints":{"allow":["GET","POST","PUT","PATCH","DELETE"]}}],"collection":[{"href":"https:\/\/www.dbu.de\/en\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/www.dbu.de\/en\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/www.dbu.de\/en\/wp-json\/wp\/v2\/users\/11"}],"replies":[{"embeddable":true,"href":"https:\/\/www.dbu.de\/en\/wp-json\/wp\/v2\/comments?post=193482"}]}}