{"id":141144,"date":"2025-05-30T11:16:48","date_gmt":"2025-05-30T09:16:48","guid":{"rendered":"https:\/\/www.dbu.de\/app\/uploads\/dbu-media-2025-pm-welterbetag-krimidinner-domschule-schleswig.jpg"},"modified":"2025-05-30T11:16:59","modified_gmt":"2025-05-30T09:16:59","slug":"cover-des-krimidinner-spiels-mord-auf-dem-grund-der-wikinger-2","status":"inherit","type":"attachment","link":"https:\/\/www.dbu.de\/en\/cover-des-krimidinner-spiels-mord-auf-dem-grund-der-wikinger-2\/","title":{"rendered":"Cover des Krimidinner-Spiels \u201eMord auf dem Grund der Wikinger"},"author":9,"featured_media":0,"comment_status":"closed","ping_status":"closed","template":"","meta":[],"class_list":["post-141144","attachment","type-attachment","status-inherit","hentry"],"meta_box":{"dbu_image_usage":"","dbu_image_download":"","dbu_image_copyright":"","dbu_image_copyright_hidden":""},"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/www.dbu.de\/app\/uploads\/dbu-media-2025-pm-welterbetag-krimidinner-domschule-schleswig.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"599\" src=\"https:\/\/www.dbu.de\/app\/uploads\/dbu-media-2025-pm-welterbetag-krimidinner-domschule-schleswig-800x599.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/www.dbu.de\/app\/uploads\/dbu-media-2025-pm-welterbetag-krimidinner-domschule-schleswig-800x599.jpg 800w, https:\/\/www.dbu.de\/app\/uploads\/dbu-media-2025-pm-welterbetag-krimidinner-domschule-schleswig-400x300.jpg 400w, https:\/\/www.dbu.de\/app\/uploads\/dbu-media-2025-pm-welterbetag-krimidinner-domschule-schleswig.jpg 1200w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/a><\/p>\n"},"caption":{"rendered":"<p>Cover des Krimidinner-Spiels \u201eMord auf dem Grund der Wikinger\u201c mit Wikinger-H\u00fctten und Windenergieanlagen<\/p>\n"},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":1200,"height":899,"file":"dbu-media-2025-pm-welterbetag-krimidinner-domschule-schleswig.jpg","filesize":351187,"sizes":{"medium":{"file":"dbu-media-2025-pm-welterbetag-krimidinner-domschule-schleswig-800x599.jpg","width":800,"height":599,"filesize":144520,"mime_type":"image\/jpeg","source_url":"https:\/\/www.dbu.de\/app\/uploads\/dbu-media-2025-pm-welterbetag-krimidinner-domschule-schleswig-800x599.jpg"},"thumbnail":{"file":"dbu-media-2025-pm-welterbetag-krimidinner-domschule-schleswig-400x300.jpg","width":400,"height":300,"filesize":64278,"mime_type":"image\/jpeg","source_url":"https:\/\/www.dbu.de\/app\/uploads\/dbu-media-2025-pm-welterbetag-krimidinner-domschule-schleswig-400x300.jpg"},"full":{"file":"dbu-media-2025-pm-welterbetag-krimidinner-domschule-schleswig.jpg","width":1200,"height":899,"mime_type":"image\/jpeg","source_url":"https:\/\/www.dbu.de\/app\/uploads\/dbu-media-2025-pm-welterbetag-krimidinner-domschule-schleswig.jpg"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"Cover des Krimidinner-Spiels \u201eMord auf dem Grund der Wikinger\u201c mit Wikinger-H\u00fctten und Windenergieanlagen","created_timestamp":"0","copyright":"Domschule Schleswig\r\rRechtliches:\rDie Verwendung dieses Bildes ist ausschlie\u00dflich im Rahmen redaktioneller Berichterstattung mi","focal_length":"0","iso":"0","shutter_speed":"0","title":"Cover des Krimidinner-Spiels \u201eMord auf dem Grund der Wikinger","orientation":"1","keywords":["Deutsche Bundesstiftung Umwelt","DBU","German Federal Environmental Foundation","Stiftung","Foundation","Umwelt","Environment","Innovation","innovative","Umweltentlastung","Environmental relief","environmentally-friendly","environmentally-sound","eco-friendly","modellhaft","exemplary","Umweltschutz","Environmental protection","Ecology","Environmentalism","Schutz der Umwelt","Protection of the environment","angewandte Umweltforschung","Applied environmental research","Architektur und Bauwesen","architecture and Building industry","Energietechnik","Energy management","Kreislauff\u00fchrung und Emissionsminderung","Circuitry and Emission reduction","Naturschutz","Nature conservation","Nature protection","Stipendienprogramm","Scholarship programme","Umwelt und Kulturg\u00fcter","Environment and cultural assets","umwelt- und gesundheitsfreundliche Verfahren und Produkte","Ecological and healthy procedures and products","Umweltbildung","Environmental education","umweltgerechte Landnutzung","Ecological land use","Umweltinformationsvermittlung","Provision of environmental information","Umweltkommunikation und Umweltmanagement in der mittelst\u00e4ndisch","Environmental communication and eco-management for small- and me","Deutscher Umweltpreis","German Environmental Award"]}},"post":null,"source_url":"https:\/\/www.dbu.de\/app\/uploads\/dbu-media-2025-pm-welterbetag-krimidinner-domschule-schleswig.jpg","filename":"dbu-media-2025-pm-welterbetag-krimidinner-domschule-schleswig.jpg","filesize":351187,"_links":{"self":[{"href":"https:\/\/www.dbu.de\/en\/wp-json\/wp\/v2\/media\/141144","targetHints":{"allow":["GET","POST","PUT","PATCH","DELETE"]}}],"collection":[{"href":"https:\/\/www.dbu.de\/en\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/www.dbu.de\/en\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/www.dbu.de\/en\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/www.dbu.de\/en\/wp-json\/wp\/v2\/comments?post=141144"}]}}